{"id":16191,"date":"2025-09-26T17:02:58","date_gmt":"2025-09-26T20:02:58","guid":{"rendered":"https:\/\/prodelcobre.cl\/nueva\/?page_id=16191"},"modified":"2026-05-11T11:41:44","modified_gmt":"2026-05-11T14:41:44","slug":"homev2","status":"publish","type":"page","link":"https:\/\/prodelcobre.cl\/nueva\/homev2\/","title":{"rendered":"Revista Profesionales del Cobre"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"16191\" class=\"elementor elementor-16191\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-3189ffbb elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"3189ffbb\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-17dee253\" data-id=\"17dee253\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7a2a943 elementor-widget elementor-widget-html\" data-id=\"7a2a943\" data-element_type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<a href=\"https:\/\/miningdusts.cl\/\" rel=\"follow\" target=\"_blank\"><video autoplay=\"\" loop=\"\" muted=\"\" playsinline=\"\" style=\"max-width: 100%\" height:auto=\"\">\n<source src=\"https:\/\/amagazine.cl\/wp-content\/uploads\/2024\/07\/mining.webm\">\n\t<\/video><\/a>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-1f6362b0\" data-id=\"1f6362b0\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-31f688db elementor-widget elementor-widget-html\" data-id=\"31f688db\" data-element_type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<a href=\"https:\/\/www.culligan.cl\/lp-mineria\/\" target=\"_blank\"><video autoplay=\"\" loop=\"\" muted=\"\" playsinline=\"\" style=\"max-width: 100%\" height:auto=\"\">\n<source src=\"https:\/\/amagazine.cl\/wp-content\/uploads\/2025\/05\/banner-culligan.webm\">\n\t<\/video><\/a>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-1a68a888 elementor-hidden-desktop elementor-hidden-tablet elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"1a68a888\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-75eca4d1\" data-id=\"75eca4d1\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5eda3e95 elementor-widget elementor-widget-shortcode\" data-id=\"5eda3e95\" data-element_type=\"widget\" data-widget_type=\"shortcode.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-shortcode\"><div class=\"psacp-wrap psacp-slider-wrap-main\">\r\n\t<div id=\"psacp-post-slider-wrap-1\" class=\"psacp-post-slider-wrap owl-carousel psacp-design-1  psacp-clearfix\" data-conf=\"{&quot;loop&quot;:true,&quot;arrows&quot;:false,&quot;dots&quot;:false,&quot;autoplay&quot;:true,&quot;autoplay_interval&quot;:5000,&quot;speed&quot;:500,&quot;rtl&quot;:false}\"><div class=\"psacp-post-slide psacp-post-18333 psacp-post-standard psacp-has-thumb\">\r\n\t<div class=\"psacp-post-slider-content\">\r\n\t\t<a class=\"psacp-post-linkoverlay\" href=\"https:\/\/prodelcobre.cl\/nueva\/supervisores-de-minera-centinela-aprueban-huelga-con-amplio-respaldo\/\"><\/a>\r\n\t\t<div class=\"psacp-post-img-bg\" style=\"background-image:url(https:\/\/prodelcobre.cl\/nueva\/wp-content\/uploads\/2026\/05\/element5-digital-T9CXBZLUvic-unsplash-scaled.jpg); \">\r\n\t\t\t<div class=\"psacp-featured-meta\">\r\n\t\t\t\t\t\t\t\r\n\t\t\t\t<h2 class=\"psacp-post-title\">\r\n\t\t\t\t\t<a href=\"https:\/\/prodelcobre.cl\/nueva\/supervisores-de-minera-centinela-aprueban-huelga-con-amplio-respaldo\/\">Supervisores de Minera Centinela aprueban huelga con amplio respaldo<\/a>\r\n\t\t\t\t<\/h2>\r\n\r\n\t\t\t\t\t\t\t\t<div class=\"psacp-post-meta psacp-post-meta-up\">\r\n\t\t\t\t\t<span class=\"psacp-post-meta-data psacp-post-date\"><i class=\"fa fa-clock-o\"><\/i>Mayo 13, 2026<\/span>\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t<\/div>\r\n\t\t<\/div>\r\n\t<\/div>\r\n<\/div><div class=\"psacp-post-slide psacp-post-18329 psacp-post-standard psacp-has-thumb\">\r\n\t<div class=\"psacp-post-slider-content\">\r\n\t\t<a class=\"psacp-post-linkoverlay\" href=\"https:\/\/prodelcobre.cl\/nueva\/sernageomin-y-polonia-avanzan-en-cooperacion-tecnica-para-fortalecer-mineria-y-geologia\/\"><\/a>\r\n\t\t<div class=\"psacp-post-img-bg\" style=\"background-image:url(https:\/\/prodelcobre.cl\/nueva\/wp-content\/uploads\/2026\/05\/polacos-1.png); \">\r\n\t\t\t<div class=\"psacp-featured-meta\">\r\n\t\t\t\t\t\t\t\r\n\t\t\t\t<h2 class=\"psacp-post-title\">\r\n\t\t\t\t\t<a href=\"https:\/\/prodelcobre.cl\/nueva\/sernageomin-y-polonia-avanzan-en-cooperacion-tecnica-para-fortalecer-mineria-y-geologia\/\">Sernageomin y Polonia avanzan en cooperaci\u00f3n t\u00e9cnica para fortalecer miner\u00eda y geolog\u00eda<\/a>\r\n\t\t\t\t<\/h2>\r\n\r\n\t\t\t\t\t\t\t\t<div class=\"psacp-post-meta psacp-post-meta-up\">\r\n\t\t\t\t\t<span class=\"psacp-post-meta-data psacp-post-date\"><i class=\"fa fa-clock-o\"><\/i>Mayo 13, 2026<\/span>\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t<\/div>\r\n\t\t<\/div>\r\n\t<\/div>\r\n<\/div><div class=\"psacp-post-slide psacp-post-18315 psacp-post-standard psacp-has-thumb\">\r\n\t<div class=\"psacp-post-slider-content\">\r\n\t\t<a class=\"psacp-post-linkoverlay\" href=\"https:\/\/prodelcobre.cl\/nueva\/codelco-es-reconocida-por-medio-ambiente-por-compensar-emisiones-en-division-ventanas\/\"><\/a>\r\n\t\t<div class=\"psacp-post-img-bg\" style=\"background-image:url(https:\/\/prodelcobre.cl\/nueva\/wp-content\/uploads\/2026\/05\/premio_medio_ambiente3.jpeg); \">\r\n\t\t\t<div class=\"psacp-featured-meta\">\r\n\t\t\t\t\t\t\t\r\n\t\t\t\t<h2 class=\"psacp-post-title\">\r\n\t\t\t\t\t<a href=\"https:\/\/prodelcobre.cl\/nueva\/codelco-es-reconocida-por-medio-ambiente-por-compensar-emisiones-en-division-ventanas\/\">Codelco es reconocida por Medio Ambiente por compensar emisiones en Divisi\u00f3n Ventanas<\/a>\r\n\t\t\t\t<\/h2>\r\n\r\n\t\t\t\t\t\t\t\t<div class=\"psacp-post-meta psacp-post-meta-up\">\r\n\t\t\t\t\t<span class=\"psacp-post-meta-data psacp-post-date\"><i class=\"fa fa-clock-o\"><\/i>Mayo 13, 2026<\/span>\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t<\/div>\r\n\t\t<\/div>\r\n\t<\/div>\r\n<\/div><div class=\"psacp-post-slide psacp-post-18326 psacp-post-standard psacp-has-thumb\">\r\n\t<div class=\"psacp-post-slider-content\">\r\n\t\t<a class=\"psacp-post-linkoverlay\" href=\"https:\/\/prodelcobre.cl\/nueva\/subsecretario-de-mineria-destaca-medidas-proinversion-minera-en-chile-day-toronto-2026\/\"><\/a>\r\n\t\t<div class=\"psacp-post-img-bg\" style=\"background-image:url(https:\/\/prodelcobre.cl\/nueva\/wp-content\/uploads\/2026\/05\/WhatsApp-Image-2026-05-12-at-10.07.40-AM-1.jpeg); \">\r\n\t\t\t<div class=\"psacp-featured-meta\">\r\n\t\t\t\t\t\t\t\r\n\t\t\t\t<h2 class=\"psacp-post-title\">\r\n\t\t\t\t\t<a href=\"https:\/\/prodelcobre.cl\/nueva\/subsecretario-de-mineria-destaca-medidas-proinversion-minera-en-chile-day-toronto-2026\/\">Subsecretario de Miner\u00eda destaca medidas proinversi\u00f3n minera en Chile Day Toronto 2026<\/a>\r\n\t\t\t\t<\/h2>\r\n\r\n\t\t\t\t\t\t\t\t<div class=\"psacp-post-meta psacp-post-meta-up\">\r\n\t\t\t\t\t<span class=\"psacp-post-meta-data psacp-post-date\"><i class=\"fa fa-clock-o\"><\/i>Mayo 12, 2026<\/span>\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t<\/div>\r\n\t\t<\/div>\r\n\t<\/div>\r\n<\/div><div class=\"psacp-post-slide psacp-post-18323 psacp-post-standard psacp-has-thumb\">\r\n\t<div class=\"psacp-post-slider-content\">\r\n\t\t<a class=\"psacp-post-linkoverlay\" href=\"https:\/\/prodelcobre.cl\/nueva\/precio-del-cobre-alcanza-maximo-historico-de-us-629-la-libra-por-creciente-fragilidad-de-la-oferta-mundial\/\"><\/a>\r\n\t\t<div class=\"psacp-post-img-bg\" style=\"background-image:url(https:\/\/prodelcobre.cl\/nueva\/wp-content\/uploads\/2026\/05\/web.jpg); \">\r\n\t\t\t<div class=\"psacp-featured-meta\">\r\n\t\t\t\t\t\t\t\r\n\t\t\t\t<h2 class=\"psacp-post-title\">\r\n\t\t\t\t\t<a href=\"https:\/\/prodelcobre.cl\/nueva\/precio-del-cobre-alcanza-maximo-historico-de-us-629-la-libra-por-creciente-fragilidad-de-la-oferta-mundial\/\">Precio del cobre alcanza m\u00e1ximo hist\u00f3rico de US$ 6,29 la libra por creciente fragilidad de la oferta mundial<\/a>\r\n\t\t\t\t<\/h2>\r\n\r\n\t\t\t\t\t\t\t\t<div class=\"psacp-post-meta psacp-post-meta-up\">\r\n\t\t\t\t\t<span class=\"psacp-post-meta-data psacp-post-date\"><i class=\"fa fa-clock-o\"><\/i>Mayo 12, 2026<\/span>\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t<\/div>\r\n\t\t<\/div>\r\n\t<\/div>\r\n<\/div><div class=\"psacp-post-slide psacp-post-18317 psacp-post-standard psacp-has-thumb\">\r\n\t<div class=\"psacp-post-slider-content\">\r\n\t\t<a class=\"psacp-post-linkoverlay\" href=\"https:\/\/prodelcobre.cl\/nueva\/golpe-al-transporte-costos-se-disparan-113-en-abril-por-fuerte-alza-del-diesel\/\"><\/a>\r\n\t\t<div class=\"psacp-post-img-bg\" style=\"background-image:url(https:\/\/prodelcobre.cl\/nueva\/wp-content\/uploads\/2026\/05\/CORTESIA-INE-1.jpg); \">\r\n\t\t\t<div class=\"psacp-featured-meta\">\r\n\t\t\t\t\t\t\t\r\n\t\t\t\t<h2 class=\"psacp-post-title\">\r\n\t\t\t\t\t<a href=\"https:\/\/prodelcobre.cl\/nueva\/golpe-al-transporte-costos-se-disparan-113-en-abril-por-fuerte-alza-del-diesel\/\">Golpe al transporte: costos se disparan 11,3% en abril por fuerte alza del di\u00e9sel<\/a>\r\n\t\t\t\t<\/h2>\r\n\r\n\t\t\t\t\t\t\t\t<div class=\"psacp-post-meta psacp-post-meta-up\">\r\n\t\t\t\t\t<span class=\"psacp-post-meta-data psacp-post-date\"><i class=\"fa fa-clock-o\"><\/i>Mayo 12, 2026<\/span>\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t<\/div>\r\n\t\t<\/div>\r\n\t<\/div>\r\n<\/div><div class=\"psacp-post-slide psacp-post-18309 psacp-post-standard psacp-has-thumb\">\r\n\t<div class=\"psacp-post-slider-content\">\r\n\t\t<a class=\"psacp-post-linkoverlay\" href=\"https:\/\/prodelcobre.cl\/nueva\/enami-amplia-plazo-para-venta-de-400-mil-toneladas-de-minerales-de-oro-en-stock\/\"><\/a>\r\n\t\t<div class=\"psacp-post-img-bg\" style=\"background-image:url(https:\/\/prodelcobre.cl\/nueva\/wp-content\/uploads\/2026\/05\/CORTESIA-ENAMI.png); \">\r\n\t\t\t<div class=\"psacp-featured-meta\">\r\n\t\t\t\t\t\t\t\r\n\t\t\t\t<h2 class=\"psacp-post-title\">\r\n\t\t\t\t\t<a href=\"https:\/\/prodelcobre.cl\/nueva\/enami-amplia-plazo-para-venta-de-400-mil-toneladas-de-minerales-de-oro-en-stock\/\">ENAMI ampl\u00eda plazo para venta de 400 mil toneladas de minerales de oro en stock<\/a>\r\n\t\t\t\t<\/h2>\r\n\r\n\t\t\t\t\t\t\t\t<div class=\"psacp-post-meta psacp-post-meta-up\">\r\n\t\t\t\t\t<span class=\"psacp-post-meta-data psacp-post-date\"><i class=\"fa fa-clock-o\"><\/i>Mayo 12, 2026<\/span>\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t<\/div>\r\n\t\t<\/div>\r\n\t<\/div>\r\n<\/div>\t<\/div>\r\n<\/div><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2c0e680e elementor-section-full_width elementor-hidden-desktop elementor-hidden-tablet elementor-section-height-default elementor-section-height-default\" data-id=\"2c0e680e\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-607abebc\" data-id=\"607abebc\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2f12d21 elementor-hidden-desktop elementor-hidden-tablet elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2f12d21\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-31f9899\" data-id=\"31f9899\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-74a7c140 meta-visibility-show title_position_default title_hover_border_default title-default img_hover_animation_default meta_position_default grid-hover-overlay-type-always tpg-el-box-border-enable tpg-border-bottom-disable elementor-widget elementor-widget-tpg-list-layout\" data-id=\"74a7c140\" data-element_type=\"widget\" data-widget_type=\"tpg-list-layout.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n        <div class=\"rt-container-fluid rt-tpg-container tpg-el-main-wrapper list-layout1-main \"\n             data-sc-id=\"elementor\"\n             id=\"rt-tpg-container-1372113884\"\n             data-layout=\"list-layout1\"\n             data-grid-style=\"tpg-even\"\n             data-el-settings=''\n             data-el-query=''\n             data-el-path=''\n        >\n\t\t\t            <div class='tpg-header-wrapper '>\n\t\t\t\t            <\/div>\n\n            <div data-title=\"Loading ...\" class=\"rt-row rt-content-loader list-layout1 tpg-even list-behaviour list-layout-wrapper\">\n\t\t\t\t\n<div class=\"rt-col-md-12 rt-col-sm-12 rt-col-xs-12 default rt-list-item rt-grid-item\" data-id=\"18333\">\n\t<div class=\"rt-holder tpg-post-holder \">\n\t\t<div class=\"rt-detail rt-el-content-wrapper\">\n\t\t\t\t\t\t\t<div class=\"rt-img-holder tpg-el-image-wrap has-thumbnail\">\n\t\t\t\t\t<a data-id=\"18333\" href=\"https:\/\/prodelcobre.cl\/nueva\/supervisores-de-minera-centinela-aprueban-huelga-con-amplio-respaldo\/\" class=\"tpg-post-link\" target=\"_self\">                        <img fetchpriority=\"high\" decoding=\"async\" src=\"https:\/\/prodelcobre.cl\/nueva\/wp-content\/uploads\/2026\/05\/element5-digital-T9CXBZLUvic-unsplash-768x512.jpg\"\n                             class=\"rt-img-responsive\"\n                             width=\"640\"\n                             height=\"427\"\n                             alt=\"Supervisores de Minera Centinela aprueban huelga con amplio respaldo\">\n\t\t\t\t\t\t\n\t\t\t\t\t\t\t\n\t\t<\/a>\n\t\t        <div class=\"overlay grid-hover-content\"><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\n\t\t\t<div class=\"post-right-content\">\n\t\t\t\t<div class=\"entry-title-wrapper\"><h5 class=\"entry-title\"><a data-id=\"18333\" href=\"https:\/\/prodelcobre.cl\/nueva\/supervisores-de-minera-centinela-aprueban-huelga-con-amplio-respaldo\/\" class=\"tpg-post-link\" target=\"_self\">Supervisores de Minera Centinela aprueban huelga con amplio respaldo<\/a><\/h5><\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"post-meta-tags rt-el-post-meta\">\n\t\t\t\t\t\t            <span class='date'>\n\t\t\t\t<i class='far fa-calendar-alt '><\/i>\t\t\t\t                    <a href=\"https:\/\/prodelcobre.cl\/nueva\/2026\/05\/13\/\">\n\t\t\t\t\tMayo 13, 2026\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"tpg-excerpt tpg-el-excerpt\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"tpg-excerpt-inner\">\n\t\t\t\t\t\t\t\tImagen referencial. Este martes 12, el Sindicato de Supervisores de Minera Centinela aprob\u00f3 la...\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\n<div class=\"rt-col-md-12 rt-col-sm-12 rt-col-xs-12 default rt-list-item rt-grid-item\" data-id=\"18329\">\n\t<div class=\"rt-holder tpg-post-holder \">\n\t\t<div class=\"rt-detail rt-el-content-wrapper\">\n\t\t\t\t\t\t\t<div class=\"rt-img-holder tpg-el-image-wrap has-thumbnail\">\n\t\t\t\t\t<a data-id=\"18329\" href=\"https:\/\/prodelcobre.cl\/nueva\/sernageomin-y-polonia-avanzan-en-cooperacion-tecnica-para-fortalecer-mineria-y-geologia\/\" class=\"tpg-post-link\" target=\"_self\">                        <img decoding=\"async\" src=\"https:\/\/prodelcobre.cl\/nueva\/wp-content\/uploads\/2026\/05\/polacos-1-768x431.png\"\n                             class=\"rt-img-responsive\"\n                             width=\"640\"\n                             height=\"359\"\n                             alt=\"Sernageomin y Polonia avanzan en cooperaci\u00f3n t\u00e9cnica para fortalecer miner\u00eda y geolog\u00eda\">\n\t\t\t\t\t\t\n\t\t\t\t\t\t\t\n\t\t<\/a>\n\t\t        <div class=\"overlay grid-hover-content\"><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\n\t\t\t<div class=\"post-right-content\">\n\t\t\t\t<div class=\"entry-title-wrapper\"><h5 class=\"entry-title\"><a data-id=\"18329\" href=\"https:\/\/prodelcobre.cl\/nueva\/sernageomin-y-polonia-avanzan-en-cooperacion-tecnica-para-fortalecer-mineria-y-geologia\/\" class=\"tpg-post-link\" target=\"_self\">Sernageomin y Polonia avanzan en cooperaci\u00f3n t\u00e9cnica para fortalecer miner\u00eda y geolog\u00eda<\/a><\/h5><\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"post-meta-tags rt-el-post-meta\">\n\t\t\t\t\t\t            <span class='date'>\n\t\t\t\t<i class='far fa-calendar-alt '><\/i>\t\t\t\t                    <a href=\"https:\/\/prodelcobre.cl\/nueva\/2026\/05\/13\/\">\n\t\t\t\t\tMayo 13, 2026\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"tpg-excerpt tpg-el-excerpt\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"tpg-excerpt-inner\">\n\t\t\t\t\t\t\t\tImagen: Sernageomin. La reuni\u00f3n entre autoridades de ambos pa\u00edses permiti\u00f3 definir l\u00edneas de trabajo...\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\n<div class=\"rt-col-md-12 rt-col-sm-12 rt-col-xs-12 default rt-list-item rt-grid-item\" data-id=\"18315\">\n\t<div class=\"rt-holder tpg-post-holder \">\n\t\t<div class=\"rt-detail rt-el-content-wrapper\">\n\t\t\t\t\t\t\t<div class=\"rt-img-holder tpg-el-image-wrap has-thumbnail\">\n\t\t\t\t\t<a data-id=\"18315\" href=\"https:\/\/prodelcobre.cl\/nueva\/codelco-es-reconocida-por-medio-ambiente-por-compensar-emisiones-en-division-ventanas\/\" class=\"tpg-post-link\" target=\"_self\">                        <img decoding=\"async\" src=\"https:\/\/prodelcobre.cl\/nueva\/wp-content\/uploads\/2026\/05\/premio_medio_ambiente3-768x512.jpeg\"\n                             class=\"rt-img-responsive\"\n                             width=\"640\"\n                             height=\"427\"\n                             alt=\"Codelco es reconocida por Medio Ambiente por compensar emisiones en Divisi\u00f3n Ventanas\">\n\t\t\t\t\t\t\n\t\t\t\t\t\t\t\n\t\t<\/a>\n\t\t        <div class=\"overlay grid-hover-content\"><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\n\t\t\t<div class=\"post-right-content\">\n\t\t\t\t<div class=\"entry-title-wrapper\"><h5 class=\"entry-title\"><a data-id=\"18315\" href=\"https:\/\/prodelcobre.cl\/nueva\/codelco-es-reconocida-por-medio-ambiente-por-compensar-emisiones-en-division-ventanas\/\" class=\"tpg-post-link\" target=\"_self\">Codelco es reconocida por Medio Ambiente por compensar emisiones en Divisi\u00f3n Ventanas<\/a><\/h5><\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"post-meta-tags rt-el-post-meta\">\n\t\t\t\t\t\t            <span class='date'>\n\t\t\t\t<i class='far fa-calendar-alt '><\/i>\t\t\t\t                    <a href=\"https:\/\/prodelcobre.cl\/nueva\/2026\/05\/13\/\">\n\t\t\t\t\tMayo 13, 2026\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"tpg-excerpt tpg-el-excerpt\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"tpg-excerpt-inner\">\n\t\t\t\t\t\t\t\tImagen: Codelco. La minera estatal logr\u00f3 compensar la totalidad de las emisiones de CO\u2082 asociadas a...\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\n<div class=\"rt-col-md-12 rt-col-sm-12 rt-col-xs-12 default rt-list-item rt-grid-item\" data-id=\"18326\">\n\t<div class=\"rt-holder tpg-post-holder \">\n\t\t<div class=\"rt-detail rt-el-content-wrapper\">\n\t\t\t\t\t\t\t<div class=\"rt-img-holder tpg-el-image-wrap has-thumbnail\">\n\t\t\t\t\t<a data-id=\"18326\" href=\"https:\/\/prodelcobre.cl\/nueva\/subsecretario-de-mineria-destaca-medidas-proinversion-minera-en-chile-day-toronto-2026\/\" class=\"tpg-post-link\" target=\"_self\">                        <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/prodelcobre.cl\/nueva\/wp-content\/uploads\/2026\/05\/WhatsApp-Image-2026-05-12-at-10.07.40-AM-1-768x512.jpeg\"\n                             class=\"rt-img-responsive\"\n                             width=\"640\"\n                             height=\"427\"\n                             alt=\"Subsecretario de Miner\u00eda destaca medidas proinversi\u00f3n minera en Chile Day Toronto 2026\">\n\t\t\t\t\t\t\n\t\t\t\t\t\t\t\n\t\t<\/a>\n\t\t        <div class=\"overlay grid-hover-content\"><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\n\t\t\t<div class=\"post-right-content\">\n\t\t\t\t<div class=\"entry-title-wrapper\"><h5 class=\"entry-title\"><a data-id=\"18326\" href=\"https:\/\/prodelcobre.cl\/nueva\/subsecretario-de-mineria-destaca-medidas-proinversion-minera-en-chile-day-toronto-2026\/\" class=\"tpg-post-link\" target=\"_self\">Subsecretario de Miner\u00eda destaca medidas proinversi\u00f3n minera en Chile Day Toronto 2026<\/a><\/h5><\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"post-meta-tags rt-el-post-meta\">\n\t\t\t\t\t\t            <span class='date'>\n\t\t\t\t<i class='far fa-calendar-alt '><\/i>\t\t\t\t                    <a href=\"https:\/\/prodelcobre.cl\/nueva\/2026\/05\/12\/\">\n\t\t\t\t\tMayo 12, 2026\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"tpg-excerpt tpg-el-excerpt\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"tpg-excerpt-inner\">\n\t\t\t\t\t\t\t\tImagen, Ministerio de Miner\u00eda. Autoridad abord\u00f3 el programa minero del gobierno y subray\u00f3 el...\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n            <\/div>\n\n\t\t\t\n        <\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-78d032f4 elementor-section-full_width elementor-hidden-mobile elementor-section-height-default elementor-section-height-default\" data-id=\"78d032f4\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-16 elementor-top-column elementor-element elementor-element-59d81026\" data-id=\"59d81026\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-69c042eb section-title-style-style2 elementor-widget elementor-widget-tpg-section-title\" data-id=\"69c042eb\" data-element_type=\"widget\" data-widget_type=\"tpg-section-title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"rt-container-fluid rt-tpg-container tpg-el-main-wrapper clearfix  section-title-style-style2\">\n\t\t\t<div class='tpg-header-wrapper'>\n        <div class=\"tpg-widget-heading-wrapper rt-clear heading-style2 \">\n            <span class=\"tpg-widget-heading-line line-left\"><\/span>\n\t\t\t<h2 class='tpg-widget-heading'>\n\t\t\t\n\t\t\t\t                    <span>\n\t\t\t\t\t\tAvisadores\t\t\t\t\t<\/span>\n\t\t\t\t\t\n\t\t\t\t\t\t\t<\/h2>            <span class=\"tpg-widget-heading-line line-right\"><\/span>\n\n\t\t\t\n        <\/div>\n\n\t\t\n\t\t<\/div>\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-13fafd4a elementor-widget__width-initial elementor-widget elementor-widget-html\" data-id=\"13fafd4a\" data-element_type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<a href=\"https:\/\/youtu.be\/KYh0yyO7tao\" target=\"_blank\"><img loading=\"lazy\" decoding=\"async\" loading=\"lazy\" width=\"336\" height=\"189\" src=\"https:\/\/procandelaria.cl\/wp-content\/uploads\/2023\/01\/Capvideo.png\" alt=\"\" class=\"wp-image-7777\"><\/a>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-72285c47 elementor-widget elementor-widget-image\" data-id=\"72285c47\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" width=\"340\" height=\"800\" src=\"https:\/\/prodelcobre.cl\/nueva\/wp-content\/uploads\/2025\/09\/Banner-gif-Radar-minero.gif\" class=\"attachment-large size-large wp-image-16195\" alt=\"Banner-gif-Radar-minero.gif\" loading=\"lazy\" decoding=\"async\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-66 elementor-top-column elementor-element elementor-element-14528817\" data-id=\"14528817\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-1f106c06 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"1f106c06\" data-element_type=\"section\" id=\"noticias\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-42a37d75\" data-id=\"42a37d75\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-48c3e846 elementor-widget elementor-widget-shortcode\" data-id=\"48c3e846\" data-element_type=\"widget\" data-widget_type=\"shortcode.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-shortcode\"><div class=\"psacp-wrap psacp-slider-wrap-main\">\r\n\t<div id=\"psacp-post-slider-wrap-2\" class=\"psacp-post-slider-wrap owl-carousel psacp-design-1  psacp-clearfix\" data-conf=\"{&quot;loop&quot;:true,&quot;arrows&quot;:false,&quot;dots&quot;:false,&quot;autoplay&quot;:true,&quot;autoplay_interval&quot;:5000,&quot;speed&quot;:500,&quot;rtl&quot;:false}\"><div class=\"psacp-post-slide psacp-post-18333 psacp-post-standard psacp-has-thumb\">\r\n\t<div class=\"psacp-post-slider-content\">\r\n\t\t<a class=\"psacp-post-linkoverlay\" href=\"https:\/\/prodelcobre.cl\/nueva\/supervisores-de-minera-centinela-aprueban-huelga-con-amplio-respaldo\/\"><\/a>\r\n\t\t<div class=\"psacp-post-img-bg\" style=\"background-image:url(https:\/\/prodelcobre.cl\/nueva\/wp-content\/uploads\/2026\/05\/element5-digital-T9CXBZLUvic-unsplash-scaled.jpg); \">\r\n\t\t\t<div class=\"psacp-featured-meta\">\r\n\t\t\t\t\t\t\t\r\n\t\t\t\t<h2 class=\"psacp-post-title\">\r\n\t\t\t\t\t<a href=\"https:\/\/prodelcobre.cl\/nueva\/supervisores-de-minera-centinela-aprueban-huelga-con-amplio-respaldo\/\">Supervisores de Minera Centinela aprueban huelga con amplio respaldo<\/a>\r\n\t\t\t\t<\/h2>\r\n\r\n\t\t\t\t\t\t\t\t<div class=\"psacp-post-meta psacp-post-meta-up\">\r\n\t\t\t\t\t<span class=\"psacp-post-meta-data psacp-post-date\"><i class=\"fa fa-clock-o\"><\/i>Mayo 13, 2026<\/span>\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t<\/div>\r\n\t\t<\/div>\r\n\t<\/div>\r\n<\/div><div class=\"psacp-post-slide psacp-post-18329 psacp-post-standard psacp-has-thumb\">\r\n\t<div class=\"psacp-post-slider-content\">\r\n\t\t<a class=\"psacp-post-linkoverlay\" href=\"https:\/\/prodelcobre.cl\/nueva\/sernageomin-y-polonia-avanzan-en-cooperacion-tecnica-para-fortalecer-mineria-y-geologia\/\"><\/a>\r\n\t\t<div class=\"psacp-post-img-bg\" style=\"background-image:url(https:\/\/prodelcobre.cl\/nueva\/wp-content\/uploads\/2026\/05\/polacos-1.png); \">\r\n\t\t\t<div class=\"psacp-featured-meta\">\r\n\t\t\t\t\t\t\t\r\n\t\t\t\t<h2 class=\"psacp-post-title\">\r\n\t\t\t\t\t<a href=\"https:\/\/prodelcobre.cl\/nueva\/sernageomin-y-polonia-avanzan-en-cooperacion-tecnica-para-fortalecer-mineria-y-geologia\/\">Sernageomin y Polonia avanzan en cooperaci\u00f3n t\u00e9cnica para fortalecer miner\u00eda y geolog\u00eda<\/a>\r\n\t\t\t\t<\/h2>\r\n\r\n\t\t\t\t\t\t\t\t<div class=\"psacp-post-meta psacp-post-meta-up\">\r\n\t\t\t\t\t<span class=\"psacp-post-meta-data psacp-post-date\"><i class=\"fa fa-clock-o\"><\/i>Mayo 13, 2026<\/span>\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t<\/div>\r\n\t\t<\/div>\r\n\t<\/div>\r\n<\/div><div class=\"psacp-post-slide psacp-post-18315 psacp-post-standard psacp-has-thumb\">\r\n\t<div class=\"psacp-post-slider-content\">\r\n\t\t<a class=\"psacp-post-linkoverlay\" href=\"https:\/\/prodelcobre.cl\/nueva\/codelco-es-reconocida-por-medio-ambiente-por-compensar-emisiones-en-division-ventanas\/\"><\/a>\r\n\t\t<div class=\"psacp-post-img-bg\" style=\"background-image:url(https:\/\/prodelcobre.cl\/nueva\/wp-content\/uploads\/2026\/05\/premio_medio_ambiente3.jpeg); \">\r\n\t\t\t<div class=\"psacp-featured-meta\">\r\n\t\t\t\t\t\t\t\r\n\t\t\t\t<h2 class=\"psacp-post-title\">\r\n\t\t\t\t\t<a href=\"https:\/\/prodelcobre.cl\/nueva\/codelco-es-reconocida-por-medio-ambiente-por-compensar-emisiones-en-division-ventanas\/\">Codelco es reconocida por Medio Ambiente por compensar emisiones en Divisi\u00f3n Ventanas<\/a>\r\n\t\t\t\t<\/h2>\r\n\r\n\t\t\t\t\t\t\t\t<div class=\"psacp-post-meta psacp-post-meta-up\">\r\n\t\t\t\t\t<span class=\"psacp-post-meta-data psacp-post-date\"><i class=\"fa fa-clock-o\"><\/i>Mayo 13, 2026<\/span>\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t<\/div>\r\n\t\t<\/div>\r\n\t<\/div>\r\n<\/div><div class=\"psacp-post-slide psacp-post-18326 psacp-post-standard psacp-has-thumb\">\r\n\t<div class=\"psacp-post-slider-content\">\r\n\t\t<a class=\"psacp-post-linkoverlay\" href=\"https:\/\/prodelcobre.cl\/nueva\/subsecretario-de-mineria-destaca-medidas-proinversion-minera-en-chile-day-toronto-2026\/\"><\/a>\r\n\t\t<div class=\"psacp-post-img-bg\" style=\"background-image:url(https:\/\/prodelcobre.cl\/nueva\/wp-content\/uploads\/2026\/05\/WhatsApp-Image-2026-05-12-at-10.07.40-AM-1.jpeg); \">\r\n\t\t\t<div class=\"psacp-featured-meta\">\r\n\t\t\t\t\t\t\t\r\n\t\t\t\t<h2 class=\"psacp-post-title\">\r\n\t\t\t\t\t<a href=\"https:\/\/prodelcobre.cl\/nueva\/subsecretario-de-mineria-destaca-medidas-proinversion-minera-en-chile-day-toronto-2026\/\">Subsecretario de Miner\u00eda destaca medidas proinversi\u00f3n minera en Chile Day Toronto 2026<\/a>\r\n\t\t\t\t<\/h2>\r\n\r\n\t\t\t\t\t\t\t\t<div class=\"psacp-post-meta psacp-post-meta-up\">\r\n\t\t\t\t\t<span class=\"psacp-post-meta-data psacp-post-date\"><i class=\"fa fa-clock-o\"><\/i>Mayo 12, 2026<\/span>\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t<\/div>\r\n\t\t<\/div>\r\n\t<\/div>\r\n<\/div><div class=\"psacp-post-slide psacp-post-18323 psacp-post-standard psacp-has-thumb\">\r\n\t<div class=\"psacp-post-slider-content\">\r\n\t\t<a class=\"psacp-post-linkoverlay\" href=\"https:\/\/prodelcobre.cl\/nueva\/precio-del-cobre-alcanza-maximo-historico-de-us-629-la-libra-por-creciente-fragilidad-de-la-oferta-mundial\/\"><\/a>\r\n\t\t<div class=\"psacp-post-img-bg\" style=\"background-image:url(https:\/\/prodelcobre.cl\/nueva\/wp-content\/uploads\/2026\/05\/web.jpg); \">\r\n\t\t\t<div class=\"psacp-featured-meta\">\r\n\t\t\t\t\t\t\t\r\n\t\t\t\t<h2 class=\"psacp-post-title\">\r\n\t\t\t\t\t<a href=\"https:\/\/prodelcobre.cl\/nueva\/precio-del-cobre-alcanza-maximo-historico-de-us-629-la-libra-por-creciente-fragilidad-de-la-oferta-mundial\/\">Precio del cobre alcanza m\u00e1ximo hist\u00f3rico de US$ 6,29 la libra por creciente fragilidad de la oferta mundial<\/a>\r\n\t\t\t\t<\/h2>\r\n\r\n\t\t\t\t\t\t\t\t<div class=\"psacp-post-meta psacp-post-meta-up\">\r\n\t\t\t\t\t<span class=\"psacp-post-meta-data psacp-post-date\"><i class=\"fa fa-clock-o\"><\/i>Mayo 12, 2026<\/span>\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t<\/div>\r\n\t\t<\/div>\r\n\t<\/div>\r\n<\/div><div class=\"psacp-post-slide psacp-post-18317 psacp-post-standard psacp-has-thumb\">\r\n\t<div class=\"psacp-post-slider-content\">\r\n\t\t<a class=\"psacp-post-linkoverlay\" href=\"https:\/\/prodelcobre.cl\/nueva\/golpe-al-transporte-costos-se-disparan-113-en-abril-por-fuerte-alza-del-diesel\/\"><\/a>\r\n\t\t<div class=\"psacp-post-img-bg\" style=\"background-image:url(https:\/\/prodelcobre.cl\/nueva\/wp-content\/uploads\/2026\/05\/CORTESIA-INE-1.jpg); \">\r\n\t\t\t<div class=\"psacp-featured-meta\">\r\n\t\t\t\t\t\t\t\r\n\t\t\t\t<h2 class=\"psacp-post-title\">\r\n\t\t\t\t\t<a href=\"https:\/\/prodelcobre.cl\/nueva\/golpe-al-transporte-costos-se-disparan-113-en-abril-por-fuerte-alza-del-diesel\/\">Golpe al transporte: costos se disparan 11,3% en abril por fuerte alza del di\u00e9sel<\/a>\r\n\t\t\t\t<\/h2>\r\n\r\n\t\t\t\t\t\t\t\t<div class=\"psacp-post-meta psacp-post-meta-up\">\r\n\t\t\t\t\t<span class=\"psacp-post-meta-data psacp-post-date\"><i class=\"fa fa-clock-o\"><\/i>Mayo 12, 2026<\/span>\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t<\/div>\r\n\t\t<\/div>\r\n\t<\/div>\r\n<\/div><div class=\"psacp-post-slide psacp-post-18309 psacp-post-standard psacp-has-thumb\">\r\n\t<div class=\"psacp-post-slider-content\">\r\n\t\t<a class=\"psacp-post-linkoverlay\" href=\"https:\/\/prodelcobre.cl\/nueva\/enami-amplia-plazo-para-venta-de-400-mil-toneladas-de-minerales-de-oro-en-stock\/\"><\/a>\r\n\t\t<div class=\"psacp-post-img-bg\" style=\"background-image:url(https:\/\/prodelcobre.cl\/nueva\/wp-content\/uploads\/2026\/05\/CORTESIA-ENAMI.png); \">\r\n\t\t\t<div class=\"psacp-featured-meta\">\r\n\t\t\t\t\t\t\t\r\n\t\t\t\t<h2 class=\"psacp-post-title\">\r\n\t\t\t\t\t<a href=\"https:\/\/prodelcobre.cl\/nueva\/enami-amplia-plazo-para-venta-de-400-mil-toneladas-de-minerales-de-oro-en-stock\/\">ENAMI ampl\u00eda plazo para venta de 400 mil toneladas de minerales de oro en stock<\/a>\r\n\t\t\t\t<\/h2>\r\n\r\n\t\t\t\t\t\t\t\t<div class=\"psacp-post-meta psacp-post-meta-up\">\r\n\t\t\t\t\t<span class=\"psacp-post-meta-data psacp-post-date\"><i class=\"fa fa-clock-o\"><\/i>Mayo 12, 2026<\/span>\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t<\/div>\r\n\t\t<\/div>\r\n\t<\/div>\r\n<\/div>\t<\/div>\r\n<\/div><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-70bd710 meta-visibility-show title_position_default title_hover_border_default title-default img_hover_animation_default meta_position_default grid-hover-overlay-type-always tpg-el-box-border-enable tpg-border-bottom-disable elementor-widget elementor-widget-tpg-list-layout\" data-id=\"70bd710\" data-element_type=\"widget\" data-widget_type=\"tpg-list-layout.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n        <div class=\"rt-container-fluid rt-tpg-container tpg-el-main-wrapper list-layout1-main \"\n             data-sc-id=\"elementor\"\n             id=\"rt-tpg-container-2258312972\"\n             data-layout=\"list-layout1\"\n             data-grid-style=\"tpg-even\"\n             data-el-settings=''\n             data-el-query=''\n             data-el-path=''\n        >\n\t\t\t            <div class='tpg-header-wrapper '>\n\t\t\t\t            <\/div>\n\n            <div data-title=\"Loading ...\" class=\"rt-row rt-content-loader list-layout1 tpg-even list-behaviour list-layout-wrapper\">\n\t\t\t\t\n<div class=\"rt-col-md-12 rt-col-sm-12 rt-col-xs-12 default rt-list-item rt-grid-item\" data-id=\"18333\">\n\t<div class=\"rt-holder tpg-post-holder \">\n\t\t<div class=\"rt-detail rt-el-content-wrapper\">\n\t\t\t\t\t\t\t<div class=\"rt-img-holder tpg-el-image-wrap has-thumbnail\">\n\t\t\t\t\t<a data-id=\"18333\" href=\"https:\/\/prodelcobre.cl\/nueva\/supervisores-de-minera-centinela-aprueban-huelga-con-amplio-respaldo\/\" class=\"tpg-post-link\" target=\"_self\">                        <img fetchpriority=\"high\" decoding=\"async\" src=\"https:\/\/prodelcobre.cl\/nueva\/wp-content\/uploads\/2026\/05\/element5-digital-T9CXBZLUvic-unsplash-768x512.jpg\"\n                             class=\"rt-img-responsive\"\n                             width=\"640\"\n                             height=\"427\"\n                             alt=\"Supervisores de Minera Centinela aprueban huelga con amplio respaldo\">\n\t\t\t\t\t\t\n\t\t\t\t\t\t\t\n\t\t<\/a>\n\t\t        <div class=\"overlay grid-hover-content\"><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\n\t\t\t<div class=\"post-right-content\">\n\t\t\t\t<div class=\"entry-title-wrapper\"><h5 class=\"entry-title\"><a data-id=\"18333\" href=\"https:\/\/prodelcobre.cl\/nueva\/supervisores-de-minera-centinela-aprueban-huelga-con-amplio-respaldo\/\" class=\"tpg-post-link\" target=\"_self\">Supervisores de Minera Centinela aprueban huelga con amplio respaldo<\/a><\/h5><\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"post-meta-tags rt-el-post-meta\">\n\t\t\t\t\t\t            <span class='date'>\n\t\t\t\t<i class='far fa-calendar-alt '><\/i>\t\t\t\t                    <a href=\"https:\/\/prodelcobre.cl\/nueva\/2026\/05\/13\/\">\n\t\t\t\t\tMayo 13, 2026\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"tpg-excerpt tpg-el-excerpt\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"tpg-excerpt-inner\">\n\t\t\t\t\t\t\t\tImagen referencial. Este martes 12, el Sindicato de Supervisores de Minera Centinela aprob\u00f3 la...\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\n<div class=\"rt-col-md-12 rt-col-sm-12 rt-col-xs-12 default rt-list-item rt-grid-item\" data-id=\"18329\">\n\t<div class=\"rt-holder tpg-post-holder \">\n\t\t<div class=\"rt-detail rt-el-content-wrapper\">\n\t\t\t\t\t\t\t<div class=\"rt-img-holder tpg-el-image-wrap has-thumbnail\">\n\t\t\t\t\t<a data-id=\"18329\" href=\"https:\/\/prodelcobre.cl\/nueva\/sernageomin-y-polonia-avanzan-en-cooperacion-tecnica-para-fortalecer-mineria-y-geologia\/\" class=\"tpg-post-link\" target=\"_self\">                        <img decoding=\"async\" src=\"https:\/\/prodelcobre.cl\/nueva\/wp-content\/uploads\/2026\/05\/polacos-1-768x431.png\"\n                             class=\"rt-img-responsive\"\n                             width=\"640\"\n                             height=\"359\"\n                             alt=\"Sernageomin y Polonia avanzan en cooperaci\u00f3n t\u00e9cnica para fortalecer miner\u00eda y geolog\u00eda\">\n\t\t\t\t\t\t\n\t\t\t\t\t\t\t\n\t\t<\/a>\n\t\t        <div class=\"overlay grid-hover-content\"><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\n\t\t\t<div class=\"post-right-content\">\n\t\t\t\t<div class=\"entry-title-wrapper\"><h5 class=\"entry-title\"><a data-id=\"18329\" href=\"https:\/\/prodelcobre.cl\/nueva\/sernageomin-y-polonia-avanzan-en-cooperacion-tecnica-para-fortalecer-mineria-y-geologia\/\" class=\"tpg-post-link\" target=\"_self\">Sernageomin y Polonia avanzan en cooperaci\u00f3n t\u00e9cnica para fortalecer miner\u00eda y geolog\u00eda<\/a><\/h5><\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"post-meta-tags rt-el-post-meta\">\n\t\t\t\t\t\t            <span class='date'>\n\t\t\t\t<i class='far fa-calendar-alt '><\/i>\t\t\t\t                    <a href=\"https:\/\/prodelcobre.cl\/nueva\/2026\/05\/13\/\">\n\t\t\t\t\tMayo 13, 2026\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"tpg-excerpt tpg-el-excerpt\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"tpg-excerpt-inner\">\n\t\t\t\t\t\t\t\tImagen: Sernageomin. La reuni\u00f3n entre autoridades de ambos pa\u00edses permiti\u00f3 definir l\u00edneas de trabajo...\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\n<div class=\"rt-col-md-12 rt-col-sm-12 rt-col-xs-12 default rt-list-item rt-grid-item\" data-id=\"18315\">\n\t<div class=\"rt-holder tpg-post-holder \">\n\t\t<div class=\"rt-detail rt-el-content-wrapper\">\n\t\t\t\t\t\t\t<div class=\"rt-img-holder tpg-el-image-wrap has-thumbnail\">\n\t\t\t\t\t<a data-id=\"18315\" href=\"https:\/\/prodelcobre.cl\/nueva\/codelco-es-reconocida-por-medio-ambiente-por-compensar-emisiones-en-division-ventanas\/\" class=\"tpg-post-link\" target=\"_self\">                        <img decoding=\"async\" src=\"https:\/\/prodelcobre.cl\/nueva\/wp-content\/uploads\/2026\/05\/premio_medio_ambiente3-768x512.jpeg\"\n                             class=\"rt-img-responsive\"\n                             width=\"640\"\n                             height=\"427\"\n                             alt=\"Codelco es reconocida por Medio Ambiente por compensar emisiones en Divisi\u00f3n Ventanas\">\n\t\t\t\t\t\t\n\t\t\t\t\t\t\t\n\t\t<\/a>\n\t\t        <div class=\"overlay grid-hover-content\"><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\n\t\t\t<div class=\"post-right-content\">\n\t\t\t\t<div class=\"entry-title-wrapper\"><h5 class=\"entry-title\"><a data-id=\"18315\" href=\"https:\/\/prodelcobre.cl\/nueva\/codelco-es-reconocida-por-medio-ambiente-por-compensar-emisiones-en-division-ventanas\/\" class=\"tpg-post-link\" target=\"_self\">Codelco es reconocida por Medio Ambiente por compensar emisiones en Divisi\u00f3n Ventanas<\/a><\/h5><\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"post-meta-tags rt-el-post-meta\">\n\t\t\t\t\t\t            <span class='date'>\n\t\t\t\t<i class='far fa-calendar-alt '><\/i>\t\t\t\t                    <a href=\"https:\/\/prodelcobre.cl\/nueva\/2026\/05\/13\/\">\n\t\t\t\t\tMayo 13, 2026\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"tpg-excerpt tpg-el-excerpt\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"tpg-excerpt-inner\">\n\t\t\t\t\t\t\t\tImagen: Codelco. La minera estatal logr\u00f3 compensar la totalidad de las emisiones de CO\u2082 asociadas a...\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\n<div class=\"rt-col-md-12 rt-col-sm-12 rt-col-xs-12 default rt-list-item rt-grid-item\" data-id=\"18326\">\n\t<div class=\"rt-holder tpg-post-holder \">\n\t\t<div class=\"rt-detail rt-el-content-wrapper\">\n\t\t\t\t\t\t\t<div class=\"rt-img-holder tpg-el-image-wrap has-thumbnail\">\n\t\t\t\t\t<a data-id=\"18326\" href=\"https:\/\/prodelcobre.cl\/nueva\/subsecretario-de-mineria-destaca-medidas-proinversion-minera-en-chile-day-toronto-2026\/\" class=\"tpg-post-link\" target=\"_self\">                        <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/prodelcobre.cl\/nueva\/wp-content\/uploads\/2026\/05\/WhatsApp-Image-2026-05-12-at-10.07.40-AM-1-768x512.jpeg\"\n                             class=\"rt-img-responsive\"\n                             width=\"640\"\n                             height=\"427\"\n                             alt=\"Subsecretario de Miner\u00eda destaca medidas proinversi\u00f3n minera en Chile Day Toronto 2026\">\n\t\t\t\t\t\t\n\t\t\t\t\t\t\t\n\t\t<\/a>\n\t\t        <div class=\"overlay grid-hover-content\"><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\n\t\t\t<div class=\"post-right-content\">\n\t\t\t\t<div class=\"entry-title-wrapper\"><h5 class=\"entry-title\"><a data-id=\"18326\" href=\"https:\/\/prodelcobre.cl\/nueva\/subsecretario-de-mineria-destaca-medidas-proinversion-minera-en-chile-day-toronto-2026\/\" class=\"tpg-post-link\" target=\"_self\">Subsecretario de Miner\u00eda destaca medidas proinversi\u00f3n minera en Chile Day Toronto 2026<\/a><\/h5><\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"post-meta-tags rt-el-post-meta\">\n\t\t\t\t\t\t            <span class='date'>\n\t\t\t\t<i class='far fa-calendar-alt '><\/i>\t\t\t\t                    <a href=\"https:\/\/prodelcobre.cl\/nueva\/2026\/05\/12\/\">\n\t\t\t\t\tMayo 12, 2026\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"tpg-excerpt tpg-el-excerpt\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"tpg-excerpt-inner\">\n\t\t\t\t\t\t\t\tImagen, Ministerio de Miner\u00eda. Autoridad abord\u00f3 el programa minero del gobierno y subray\u00f3 el...\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n            <\/div>\n\n\t\t\t\n        <\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-16 elementor-top-column elementor-element elementor-element-fb452a\" data-id=\"fb452a\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2c5fcf1b section-title-style-style2 elementor-widget elementor-widget-tpg-section-title\" data-id=\"2c5fcf1b\" data-element_type=\"widget\" data-widget_type=\"tpg-section-title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"rt-container-fluid rt-tpg-container tpg-el-main-wrapper clearfix  section-title-style-style2\">\n\t\t\t<div class='tpg-header-wrapper'>\n        <div class=\"tpg-widget-heading-wrapper rt-clear heading-style2 \">\n            <span class=\"tpg-widget-heading-line line-left\"><\/span>\n\t\t\t<h2 class='tpg-widget-heading'>\n\t\t\t\n\t\t\t\t                    <span>\n\t\t\t\t\t\tRevista Digital\t\t\t\t\t<\/span>\n\t\t\t\t\t\n\t\t\t\t\t\t\t<\/h2>            <span class=\"tpg-widget-heading-line line-right\"><\/span>\n\n\t\t\t\n        <\/div>\n\n\t\t\n\t\t<\/div>\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-43ef313f elementor-widget elementor-widget-image\" data-id=\"43ef313f\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/prodelcobre.cl\/nueva\/edicion-numero-22\/\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" width=\"2200\" height=\"2200\" src=\"https:\/\/prodelcobre.cl\/nueva\/wp-content\/uploads\/2025\/07\/banners-02.jpg\" class=\"attachment-large size-large wp-image-15742\" alt=\"banners-02\" srcset=\"https:\/\/prodelcobre.cl\/nueva\/wp-content\/uploads\/2025\/07\/banners-02.jpg 2200w, https:\/\/prodelcobre.cl\/nueva\/wp-content\/uploads\/2025\/07\/banners-02-150x150.jpg 150w, https:\/\/prodelcobre.cl\/nueva\/wp-content\/uploads\/2025\/07\/banners-02-768x768.jpg 768w, https:\/\/prodelcobre.cl\/nueva\/wp-content\/uploads\/2025\/07\/banners-02-1536x1536.jpg 1536w\" sizes=\"auto, (max-width: 2200px) 100vw, 2200px\" loading=\"lazy\" decoding=\"async\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-7bfb4904 elementor-section-full_width elementor-hidden-mobile elementor-section-height-default elementor-section-height-default\" data-id=\"7bfb4904\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-3b34769d\" data-id=\"3b34769d\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2353282c elementor-widget elementor-widget-html\" data-id=\"2353282c\" data-element_type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<a href=\"https:\/\/www.krah.cl\/\" target=\"_blank\"><video autoplay=\"\" loop=\"\" muted=\"\" playsinline=\"\" style=\"max-width: 100%\" height:auto=\"\">\n<source src=\"https:\/\/amagazine.cl\/wp-content\/uploads\/2024\/11\/banner-krah.webm\">\n\t<\/video><\/a>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-107f9d22\" data-id=\"107f9d22\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-424fa6b0 elementor-widget elementor-widget-image\" data-id=\"424fa6b0\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.kolff-e.com\/\" target=\"_blank\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" width=\"1233\" height=\"200\" src=\"https:\/\/prodelcobre.cl\/nueva\/wp-content\/uploads\/2025\/09\/Banner-Revista-Mineria_Mesa-de-trabajo-1.png\" class=\"attachment-large size-large wp-image-16199\" alt=\"Banner-Revista-Mineria_Mesa-de-trabajo-1.png\" srcset=\"https:\/\/prodelcobre.cl\/nueva\/wp-content\/uploads\/2025\/09\/Banner-Revista-Mineria_Mesa-de-trabajo-1.png 1233w, https:\/\/prodelcobre.cl\/nueva\/wp-content\/uploads\/2025\/09\/Banner-Revista-Mineria_Mesa-de-trabajo-1-768x125.png 768w, https:\/\/prodelcobre.cl\/nueva\/wp-content\/uploads\/2025\/09\/Banner-Revista-Mineria_Mesa-de-trabajo-1-1024x166.png 1024w\" sizes=\"auto, (max-width: 1233px) 100vw, 1233px\" loading=\"lazy\" decoding=\"async\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-8f0cf05 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"8f0cf05\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-fc767cf\" data-id=\"fc767cf\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-52591342 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"52591342\" data-element_type=\"section\" id=\"proveedores\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-e375c3b\" data-id=\"e375c3b\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1fcfd23c section-title-style-style3 meta-visibility-show title_position_default title_hover_border_default title-default img_hover_animation_default meta_position_default grid-hover-overlay-type-always tpg-el-box-border-enable tpg-border-bottom-disable elementor-widget elementor-widget-tpg-list-layout\" data-id=\"1fcfd23c\" data-element_type=\"widget\" data-widget_type=\"tpg-list-layout.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n        <div class=\"rt-container-fluid rt-tpg-container tpg-el-main-wrapper list-layout2-2-main \"\n             data-sc-id=\"elementor\"\n             id=\"rt-tpg-container-2755050145\"\n             data-layout=\"list-layout2-2\"\n             data-grid-style=\"tpg-even\"\n             data-el-settings=''\n             data-el-query=''\n             data-el-path=''\n        >\n\t\t\t            <div class='tpg-header-wrapper '>\n\t\t\t\t\n        <div class=\"tpg-widget-heading-wrapper rt-clear heading-style3 \">\n            <span class=\"tpg-widget-heading-line line-left\"><\/span>\n\t\t\t<h3 class='tpg-widget-heading'>\n\t\t\t\n\t\t\t\t                    <span>\n\t\t\t\t\t\tProveedores Mineros\t\t\t\t\t<\/span>\n\t\t\t\t\t\n\t\t\t\t\t\t\t<\/h3>            <span class=\"tpg-widget-heading-line line-right\"><\/span>\n\n\t\t\t\n        <\/div>\n\n\t\t\n\t\t            <\/div>\n\n            <div data-title=\"Loading ...\" class=\"rt-row rt-content-loader list-layout2 tpg-even list-behaviour list-layout-wrapper\">\n\t\t\t\t\n\t<!--Start Offset left & offset right column-->\n\t<div class=\"rt-col-xs-12 rt-col-md-4 rt-col-sm-5 offset-left-wrap offset-left\">\n\n\n\n\n\t<div class=\"rt-holder tpg-post-holder \">\n\t\t<div class=\"rt-detail rt-el-content-wrapper\">\n\t\t\t\t\t\t\t<div class=\"rt-img-holder tpg-el-image-wrap has-no-thumbnail\">\n\t\t\t\t\t<a data-id=\"17153\" href=\"https:\/\/prodelcobre.cl\/nueva\/environment-iot-tecnologia-inteligente-para-cerrar-la-brecha-productiva-en-las-industrias-chilenas\/\" class=\"tpg-post-link\" target=\"_self\">\t\t\n\t\t<\/a>\n\t\t        <div class=\"overlay grid-hover-content\"><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\n\t\t\t<div class=\"post-right-content\">\n\n\t\t\t\t<div class=\"entry-title-wrapper\"><h4 class=\"entry-title\"><a data-id=\"17153\" href=\"https:\/\/prodelcobre.cl\/nueva\/environment-iot-tecnologia-inteligente-para-cerrar-la-brecha-productiva-en-las-industrias-chilenas\/\" class=\"tpg-post-link\" target=\"_self\">Environment IoT: tecnolog\u00eda inteligente para cerrar la brecha productiva en las industrias chilenas<\/a><\/h4><\/div>\n\n\t\t\t\t\t\t\t\t\t<div class=\"post-meta-tags rt-el-post-meta\">\n\t\t\t\t\t\t            <span class='date'>\n\t\t\t\t<i class='far fa-calendar-alt '><\/i>\t\t\t\t                    <a href=\"https:\/\/prodelcobre.cl\/nueva\/2026\/01\/16\/\">\n\t\t\t\t\tEnero 16, 2026\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"tpg-excerpt tpg-el-excerpt\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"tpg-excerpt-inner\">\n\t\t\t\t\t\t\t\tChile atraviesa un punto de inflexi\u00f3n en materia de productividad, eficiencia operativa y adopci\u00f3n tecnol\u00f3gica. Mientras las grandes...\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\n\n\n\n<\/div> <!--End Offset left & offset right column-->\n\t<!--Start Offset left & offset right column-->\n\t<div class=\"rt-col-xs-12 rt-col-md-8 rt-col-sm-7 offset-right\">\n\n\t<!--Start .rt-row -->\n\t<div class='rt-row'>\n\n\t<!--Start right offset column -->\n\t<div class=\"rt-col-md-6 rt-col-sm-12 rt-col-xs-12 default rt-list-item rt-grid-item\" data-id=\"16740\">\n\n\n\t<div class=\"rt-holder tpg-post-holder \">\n\t\t<div class=\"rt-detail rt-el-content-wrapper\">\n\t\t\t\t\t\t\t<div class=\"rt-img-holder tpg-el-image-wrap has-thumbnail\">\n\t\t\t\t\t<a data-id=\"16740\" href=\"https:\/\/prodelcobre.cl\/nueva\/salfa-impulsa-una-mineria-mas-eficiente-y-sustentable-con-neumaticos-otr-de-alto-rendimiento\/\" class=\"tpg-post-link\" target=\"_self\"><img loading=\"lazy\" width=\"640\" height=\"490\" src=\"https:\/\/prodelcobre.cl\/nueva\/wp-content\/uploads\/2025\/11\/Sin-titulo-2.jpg\" class=\"attachment-medium_large size-medium_large wp-post-image\" alt=\"Sin t\u00edtulo-2\" loading=\"lazy\" decoding=\"async\" \/>\t\t\n\t\t<\/a>\n\t\t        <div class=\"overlay grid-hover-content\"><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\n\t\t\t<div class=\"post-right-content\">\n\n\t\t\t\t<div class=\"entry-title-wrapper\"><h4 class=\"entry-title\"><a data-id=\"16740\" href=\"https:\/\/prodelcobre.cl\/nueva\/salfa-impulsa-una-mineria-mas-eficiente-y-sustentable-con-neumaticos-otr-de-alto-rendimiento\/\" class=\"tpg-post-link\" target=\"_self\">Salfa impulsa una miner\u00eda m\u00e1s eficiente y sustentable con neum\u00e1ticos OTR de alto rendimiento<\/a><\/h4><\/div>\n\n\t\t\t\t\t\t\t\t\t<div class=\"post-meta-tags rt-el-post-meta\">\n\t\t\t\t\t\t            <span class='date'>\n\t\t\t\t<i class='far fa-calendar-alt '><\/i>\t\t\t\t                    <a href=\"https:\/\/prodelcobre.cl\/nueva\/2025\/11\/28\/\">\n\t\t\t\t\tNoviembre 28, 2025\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\n\n<\/div> <!--End right offset column -->\n\n\n\n\n\t<!--Start right offset column -->\n\t<div class=\"rt-col-md-6 rt-col-sm-12 rt-col-xs-12 default rt-list-item rt-grid-item\" data-id=\"15303\">\n\n\n\t<div class=\"rt-holder tpg-post-holder \">\n\t\t<div class=\"rt-detail rt-el-content-wrapper\">\n\t\t\t\t\t\t\t<div class=\"rt-img-holder tpg-el-image-wrap has-thumbnail\">\n\t\t\t\t\t<a data-id=\"15303\" href=\"https:\/\/prodelcobre.cl\/nueva\/sandvik-presenta-el-futuro-de-la-operacion-autonoma-de-equipos-de-perforacion-con-automine-surface-fleet\/\" class=\"tpg-post-link\" target=\"_self\"><img loading=\"lazy\" width=\"640\" height=\"396\" src=\"https:\/\/prodelcobre.cl\/nueva\/wp-content\/uploads\/2025\/06\/sandvik-web-768x475.jpg\" class=\"attachment-medium_large size-medium_large wp-post-image\" alt=\"SANDVIK\" srcset=\"https:\/\/prodelcobre.cl\/nueva\/wp-content\/uploads\/2025\/06\/sandvik-web-768x475.jpg 768w, https:\/\/prodelcobre.cl\/nueva\/wp-content\/uploads\/2025\/06\/sandvik-web.jpg 900w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" loading=\"lazy\" decoding=\"async\" \/>\t\t\n\t\t<\/a>\n\t\t        <div class=\"overlay grid-hover-content\"><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\n\t\t\t<div class=\"post-right-content\">\n\n\t\t\t\t<div class=\"entry-title-wrapper\"><h4 class=\"entry-title\"><a data-id=\"15303\" href=\"https:\/\/prodelcobre.cl\/nueva\/sandvik-presenta-el-futuro-de-la-operacion-autonoma-de-equipos-de-perforacion-con-automine-surface-fleet\/\" class=\"tpg-post-link\" target=\"_self\">Sandvik presenta el futuro de la operaci\u00f3n aut\u00f3noma de equipos de perforaci\u00f3n con AutoMine Surface Fleet<\/a><\/h4><\/div>\n\n\t\t\t\t\t\t\t\t\t<div class=\"post-meta-tags rt-el-post-meta\">\n\t\t\t\t\t\t            <span class='date'>\n\t\t\t\t<i class='far fa-calendar-alt '><\/i>\t\t\t\t                    <a href=\"https:\/\/prodelcobre.cl\/nueva\/2025\/06\/04\/\">\n\t\t\t\t\tJunio 4, 2025\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\n\n<\/div> <!--End right offset column -->\n\n\n\n\n\t<!--Start right offset column -->\n\t<div class=\"rt-col-md-6 rt-col-sm-12 rt-col-xs-12 default rt-list-item rt-grid-item\" data-id=\"14886\">\n\n\n\t<div class=\"rt-holder tpg-post-holder \">\n\t\t<div class=\"rt-detail rt-el-content-wrapper\">\n\t\t\t\t\t\t\t<div class=\"rt-img-holder tpg-el-image-wrap has-thumbnail\">\n\t\t\t\t\t<a data-id=\"14886\" href=\"https:\/\/prodelcobre.cl\/nueva\/act-mining-lanza-solucion-ia-que-potenciala-asignacion-de-flotas-en-mineria\/\" class=\"tpg-post-link\" target=\"_self\"><img loading=\"lazy\" width=\"640\" height=\"493\" src=\"https:\/\/prodelcobre.cl\/nueva\/wp-content\/uploads\/2025\/04\/FOTO-FLOTA-CAMIONES-web-768x591.jpg\" class=\"attachment-medium_large size-medium_large wp-post-image\" alt=\"ACT Mining\" srcset=\"https:\/\/prodelcobre.cl\/nueva\/wp-content\/uploads\/2025\/04\/FOTO-FLOTA-CAMIONES-web-768x591.jpg 768w, https:\/\/prodelcobre.cl\/nueva\/wp-content\/uploads\/2025\/04\/FOTO-FLOTA-CAMIONES-web.jpg 800w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" loading=\"lazy\" decoding=\"async\" \/>\t\t\n\t\t<\/a>\n\t\t        <div class=\"overlay grid-hover-content\"><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\n\t\t\t<div class=\"post-right-content\">\n\n\t\t\t\t<div class=\"entry-title-wrapper\"><h4 class=\"entry-title\"><a data-id=\"14886\" href=\"https:\/\/prodelcobre.cl\/nueva\/act-mining-lanza-solucion-ia-que-potenciala-asignacion-de-flotas-en-mineria\/\" class=\"tpg-post-link\" target=\"_self\">ACT Mining lanza soluci\u00f3n IA que potenciala asignaci\u00f3n de flotas en miner\u00eda<\/a><\/h4><\/div>\n\n\t\t\t\t\t\t\t\t\t<div class=\"post-meta-tags rt-el-post-meta\">\n\t\t\t\t\t\t            <span class='date'>\n\t\t\t\t<i class='far fa-calendar-alt '><\/i>\t\t\t\t                    <a href=\"https:\/\/prodelcobre.cl\/nueva\/2025\/04\/11\/\">\n\t\t\t\t\tAbril 11, 2025\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\n\n<\/div> <!--End right offset column -->\n\n\n\n\n\t<!--Start right offset column -->\n\t<div class=\"rt-col-md-6 rt-col-sm-12 rt-col-xs-12 default rt-list-item rt-grid-item\" data-id=\"14673\">\n\n\n\t<div class=\"rt-holder tpg-post-holder \">\n\t\t<div class=\"rt-detail rt-el-content-wrapper\">\n\t\t\t\t\t\t\t<div class=\"rt-img-holder tpg-el-image-wrap has-thumbnail\">\n\t\t\t\t\t<a data-id=\"14673\" href=\"https:\/\/prodelcobre.cl\/nueva\/nueva-empresa-se-suma-a-gremio-de-proveedores-de-la-mineria\/\" class=\"tpg-post-link\" target=\"_self\"><img loading=\"lazy\" width=\"640\" height=\"331\" src=\"https:\/\/prodelcobre.cl\/nueva\/wp-content\/uploads\/2025\/03\/Imagen-grupal-Tecfluid-1WEB-768x397.jpg\" class=\"attachment-medium_large size-medium_large wp-post-image\" alt=\"Imagen grupal Tecfluid (1)WEB\" srcset=\"https:\/\/prodelcobre.cl\/nueva\/wp-content\/uploads\/2025\/03\/Imagen-grupal-Tecfluid-1WEB-768x397.jpg 768w, https:\/\/prodelcobre.cl\/nueva\/wp-content\/uploads\/2025\/03\/Imagen-grupal-Tecfluid-1WEB.jpg 800w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" loading=\"lazy\" decoding=\"async\" \/>\t\t\n\t\t<\/a>\n\t\t        <div class=\"overlay grid-hover-content\"><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\n\t\t\t<div class=\"post-right-content\">\n\n\t\t\t\t<div class=\"entry-title-wrapper\"><h4 class=\"entry-title\"><a data-id=\"14673\" href=\"https:\/\/prodelcobre.cl\/nueva\/nueva-empresa-se-suma-a-gremio-de-proveedores-de-la-mineria\/\" class=\"tpg-post-link\" target=\"_self\">Nueva empresa se suma a gremio de proveedores de la miner\u00eda<\/a><\/h4><\/div>\n\n\t\t\t\t\t\t\t\t\t<div class=\"post-meta-tags rt-el-post-meta\">\n\t\t\t\t\t\t            <span class='date'>\n\t\t\t\t<i class='far fa-calendar-alt '><\/i>\t\t\t\t                    <a href=\"https:\/\/prodelcobre.cl\/nueva\/2025\/03\/17\/\">\n\t\t\t\t\tMarzo 17, 2025\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\n\n<\/div> <!--End right offset column -->\n\n\n\n\n\t<!--Start right offset column -->\n\t<div class=\"rt-col-md-6 rt-col-sm-12 rt-col-xs-12 default rt-list-item rt-grid-item\" data-id=\"14560\">\n\n\n\t<div class=\"rt-holder tpg-post-holder \">\n\t\t<div class=\"rt-detail rt-el-content-wrapper\">\n\t\t\t\t\t\t\t<div class=\"rt-img-holder tpg-el-image-wrap has-thumbnail\">\n\t\t\t\t\t<a data-id=\"14560\" href=\"https:\/\/prodelcobre.cl\/nueva\/syntec-exhibe-sus-soluciones-de-ingenieria-especializada-en-eweek-fluor-2025\/\" class=\"tpg-post-link\" target=\"_self\"><img loading=\"lazy\" width=\"640\" height=\"480\" src=\"https:\/\/prodelcobre.cl\/nueva\/wp-content\/uploads\/2025\/03\/FOTO-SYNTEC-EN-EWEEK-2-web-768x576.jpg\" class=\"attachment-medium_large size-medium_large wp-post-image\" alt=\"FOTO SYNTEC EN EWEEK 2-web\" srcset=\"https:\/\/prodelcobre.cl\/nueva\/wp-content\/uploads\/2025\/03\/FOTO-SYNTEC-EN-EWEEK-2-web-768x576.jpg 768w, https:\/\/prodelcobre.cl\/nueva\/wp-content\/uploads\/2025\/03\/FOTO-SYNTEC-EN-EWEEK-2-web.jpg 800w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" loading=\"lazy\" decoding=\"async\" \/>\t\t\n\t\t<\/a>\n\t\t        <div class=\"overlay grid-hover-content\"><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\n\t\t\t<div class=\"post-right-content\">\n\n\t\t\t\t<div class=\"entry-title-wrapper\"><h4 class=\"entry-title\"><a data-id=\"14560\" href=\"https:\/\/prodelcobre.cl\/nueva\/syntec-exhibe-sus-soluciones-de-ingenieria-especializada-en-eweek-fluor-2025\/\" class=\"tpg-post-link\" target=\"_self\">Syntec exhibe sus soluciones de ingenier\u00eda especializada en EWeek Fluor 2025<\/a><\/h4><\/div>\n\n\t\t\t\t\t\t\t\t\t<div class=\"post-meta-tags rt-el-post-meta\">\n\t\t\t\t\t\t            <span class='date'>\n\t\t\t\t<i class='far fa-calendar-alt '><\/i>\t\t\t\t                    <a href=\"https:\/\/prodelcobre.cl\/nueva\/2025\/03\/04\/\">\n\t\t\t\t\tMarzo 4, 2025\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\n\n<\/div> <!--End right offset column -->\n\n\n\n\n\t<!--Start right offset column -->\n\t<div class=\"rt-col-md-6 rt-col-sm-12 rt-col-xs-12 default rt-list-item rt-grid-item\" data-id=\"14555\">\n\n\n\t<div class=\"rt-holder tpg-post-holder \">\n\t\t<div class=\"rt-detail rt-el-content-wrapper\">\n\t\t\t\t\t\t\t<div class=\"rt-img-holder tpg-el-image-wrap has-thumbnail\">\n\t\t\t\t\t<a data-id=\"14555\" href=\"https:\/\/prodelcobre.cl\/nueva\/corredores-biologicos-puentes-de-vida-para-la-conservacion-en-el-peru\/\" class=\"tpg-post-link\" target=\"_self\"><img loading=\"lazy\" width=\"640\" height=\"448\" src=\"https:\/\/prodelcobre.cl\/nueva\/wp-content\/uploads\/2025\/03\/Calculo-de-huella-antropica-de-Suri-768x537.jpg\" class=\"attachment-medium_large size-medium_large wp-post-image\" alt=\"C\u00e1lculo de huella antr\u00f3pica de Suri\" srcset=\"https:\/\/prodelcobre.cl\/nueva\/wp-content\/uploads\/2025\/03\/Calculo-de-huella-antropica-de-Suri-768x537.jpg 768w, https:\/\/prodelcobre.cl\/nueva\/wp-content\/uploads\/2025\/03\/Calculo-de-huella-antropica-de-Suri.jpg 895w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" loading=\"lazy\" decoding=\"async\" \/>\t\t\n\t\t<\/a>\n\t\t        <div class=\"overlay grid-hover-content\"><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\n\t\t\t<div class=\"post-right-content\">\n\n\t\t\t\t<div class=\"entry-title-wrapper\"><h4 class=\"entry-title\"><a data-id=\"14555\" href=\"https:\/\/prodelcobre.cl\/nueva\/corredores-biologicos-puentes-de-vida-para-la-conservacion-en-el-peru\/\" class=\"tpg-post-link\" target=\"_self\">Corredores Biol\u00f3gicos: Puentes de Vida para la Conservaci\u00f3n en el Per\u00fa<\/a><\/h4><\/div>\n\n\t\t\t\t\t\t\t\t\t<div class=\"post-meta-tags rt-el-post-meta\">\n\t\t\t\t\t\t            <span class='date'>\n\t\t\t\t<i class='far fa-calendar-alt '><\/i>\t\t\t\t                    <a href=\"https:\/\/prodelcobre.cl\/nueva\/2025\/03\/04\/\">\n\t\t\t\t\tMarzo 4, 2025\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\n\n<\/div> <!--End right offset column --><\/div> <!--End .rt-row -->\n\n<\/div> <!--End Offset left & offset right column-->            <\/div>\n\n\t\t\t\n        <\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-596753d elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"596753d\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-7a30fdb\" data-id=\"7a30fdb\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8891039 elementor-widget elementor-widget-html\" data-id=\"8891039\" data-element_type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<a href=\"https:\/\/expominaperu.com\/\" target=\"_blank\" rel\"nofollow\">\n<img src=https:\/\/amagazine.cl\/wp-content\/uploads\/2026\/02\/Banner-Expomina-Peru-2026.jpg.jpeg\" alt=\"banner expomina\"\/><\/a>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-38345266\" data-id=\"38345266\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-71eebb9 elementor-widget elementor-widget-html\" data-id=\"71eebb9\" data-element_type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<a href=\"https:\/\/www.salfanyb.cl\/categoria-producto\/neumaticos\/aplicacion_prod-otr\/\" target=\"_blank\"><img decoding=\"async\" src=\"https:\/\/amagazine.cl\/wp-content\/uploads\/2025\/10\/Banner-1110x180-px.jpg\" alt=\"banner salfa west lake\"><\/a>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-88c230c elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"88c230c\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-0357556\" data-id=\"0357556\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-13443c6 section-title-style-style3 meta-visibility-show title_position_default title_hover_border_default title-default img_hover_animation_default meta_position_default grid-hover-overlay-type-always tpg-el-box-border-enable tpg-border-bottom-disable elementor-widget elementor-widget-tpg-list-layout\" data-id=\"13443c6\" data-element_type=\"widget\" data-widget_type=\"tpg-list-layout.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n        <div class=\"rt-container-fluid rt-tpg-container tpg-el-main-wrapper list-layout2-main \"\n             data-sc-id=\"elementor\"\n             id=\"rt-tpg-container-1103807224\"\n             data-layout=\"list-layout2\"\n             data-grid-style=\"tpg-even\"\n             data-el-settings=''\n             data-el-query=''\n             data-el-path=''\n        >\n\t\t\t            <div class='tpg-header-wrapper '>\n\t\t\t\t\n        <div class=\"tpg-widget-heading-wrapper rt-clear heading-style3 \">\n            <span class=\"tpg-widget-heading-line line-left\"><\/span>\n\t\t\t<h3 class='tpg-widget-heading'>\n\t\t\t\n\t\t\t\t                    <span>\n\t\t\t\t\t\tEnerg\u00eda y Mercados\t\t\t\t\t<\/span>\n\t\t\t\t\t\n\t\t\t\t\t\t\t<\/h3>            <span class=\"tpg-widget-heading-line line-right\"><\/span>\n\n\t\t\t\n        <\/div>\n\n\t\t\n\t\t            <\/div>\n\n            <div data-title=\"Loading ...\" class=\"rt-row rt-content-loader list-layout2 tpg-even list-behaviour list-layout-wrapper\">\n\t\t\t\t\n\t<!--Start Offset left & offset right column-->\n\t<div class=\"rt-col-xs-12 rt-col-md-4 rt-col-sm-5 offset-left-wrap offset-left\">\n\n\n\n\n\t<div class=\"rt-holder tpg-post-holder \">\n\t\t<div class=\"rt-detail rt-el-content-wrapper\">\n\t\t\t\t\t\t\t<div class=\"rt-img-holder tpg-el-image-wrap has-thumbnail\">\n\t\t\t\t\t<a data-id=\"18293\" href=\"https:\/\/prodelcobre.cl\/nueva\/exportaciones-chilenas-suben-12-en-enero-abril-y-el-litio-impulsa-crecimiento-record-del-comercio-exterior\/\" class=\"tpg-post-link\" target=\"_self\">                        <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/prodelcobre.cl\/nueva\/wp-content\/uploads\/2026\/05\/El-Industrial-edicion-Diciembre-2025-Enero-2026-70-768x432.png\"\n                             class=\"rt-img-responsive\"\n                             width=\"640\"\n                             height=\"360\"\n                             alt=\"Exportaciones chilenas suben 12% en enero-abril y el litio impulsa crecimiento r\u00e9cord del comercio exterior\">\n\t\t\t\t\t\t\n\t\t\t\t\t\t\t\n\t\t<\/a>\n\t\t        <div class=\"overlay grid-hover-content\"><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\n\t\t\t<div class=\"post-right-content\">\n\n\t\t\t\t<div class=\"entry-title-wrapper\"><h4 class=\"entry-title\"><a data-id=\"18293\" href=\"https:\/\/prodelcobre.cl\/nueva\/exportaciones-chilenas-suben-12-en-enero-abril-y-el-litio-impulsa-crecimiento-record-del-comercio-exterior\/\" class=\"tpg-post-link\" target=\"_self\">Exportaciones chilenas suben 12% en enero-abril y el litio impulsa crecimiento r\u00e9cord del comercio exterior<\/a><\/h4><\/div>\n\n\t\t\t\t\t\t\t\t\t<div class=\"post-meta-tags rt-el-post-meta\">\n\t\t\t\t\t\t            <span class='date'>\n\t\t\t\t<i class='far fa-calendar-alt '><\/i>\t\t\t\t                    <a href=\"https:\/\/prodelcobre.cl\/nueva\/2026\/05\/11\/\">\n\t\t\t\t\tMayo 11, 2026\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"tpg-excerpt tpg-el-excerpt\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"tpg-excerpt-inner\">\n\t\t\t\t\t\t\t\tImagen: Subsecretar\u00eda de relaciones econ\u00f3micas internacionales. El intercambio comercial del pa\u00eds alcanz\u00f3 $69.963 millones de d\u00f3lares en los...\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\n\n\n\n<\/div> <!--End Offset left & offset right column-->\n\t<!--Start Offset left & offset right column-->\n\t<div class=\"rt-col-xs-12 rt-col-md-8 rt-col-sm-7 offset-right\">\n\n\t<!--Start .rt-row -->\n\t<div class='rt-row'>\n\n\t<!--Start right offset column -->\n\t<div class=\"rt-col-md-6 rt-col-sm-12 rt-col-xs-12 default rt-list-item rt-grid-item\" data-id=\"18267\">\n\n\n\t<div class=\"rt-holder tpg-post-holder \">\n\t\t<div class=\"rt-detail rt-el-content-wrapper\">\n\t\t\t\t\t\t\t<div class=\"rt-img-holder tpg-el-image-wrap has-thumbnail\">\n\t\t\t\t\t<a data-id=\"18267\" href=\"https:\/\/prodelcobre.cl\/nueva\/ipc-de-abril-registra-alza-mensual-de-13-impulsada-por-transporte-y-vivienda\/\" class=\"tpg-post-link\" target=\"_self\"><img loading=\"lazy\" width=\"640\" height=\"427\" src=\"https:\/\/prodelcobre.cl\/nueva\/wp-content\/uploads\/2026\/05\/ipc-web2036918e7ce44449a10d61c908fa8a8f-768x512.jpg\" class=\"attachment-medium_large size-medium_large wp-post-image\" alt=\"ipc-web2036918e7ce44449a10d61c908fa8a8f\" srcset=\"https:\/\/prodelcobre.cl\/nueva\/wp-content\/uploads\/2026\/05\/ipc-web2036918e7ce44449a10d61c908fa8a8f-768x512.jpg 768w, https:\/\/prodelcobre.cl\/nueva\/wp-content\/uploads\/2026\/05\/ipc-web2036918e7ce44449a10d61c908fa8a8f.jpg 855w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" loading=\"lazy\" decoding=\"async\" \/>\t\t\n\t\t<\/a>\n\t\t        <div class=\"overlay grid-hover-content\"><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\n\t\t\t<div class=\"post-right-content\">\n\n\t\t\t\t<div class=\"entry-title-wrapper\"><h4 class=\"entry-title\"><a data-id=\"18267\" href=\"https:\/\/prodelcobre.cl\/nueva\/ipc-de-abril-registra-alza-mensual-de-13-impulsada-por-transporte-y-vivienda\/\" class=\"tpg-post-link\" target=\"_self\">IPC de abril registra alza mensual de 1,3% impulsada por transporte y vivienda<\/a><\/h4><\/div>\n\n\t\t\t\t\t\t\t\t\t<div class=\"post-meta-tags rt-el-post-meta\">\n\t\t\t\t\t\t            <span class='date'>\n\t\t\t\t<i class='far fa-calendar-alt '><\/i>\t\t\t\t                    <a href=\"https:\/\/prodelcobre.cl\/nueva\/2026\/05\/08\/\">\n\t\t\t\t\tMayo 8, 2026\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\n\n<\/div> <!--End right offset column -->\n\n\n\n\n\t<!--Start right offset column -->\n\t<div class=\"rt-col-md-6 rt-col-sm-12 rt-col-xs-12 default rt-list-item rt-grid-item\" data-id=\"18116\">\n\n\n\t<div class=\"rt-holder tpg-post-holder \">\n\t\t<div class=\"rt-detail rt-el-content-wrapper\">\n\t\t\t\t\t\t\t<div class=\"rt-img-holder tpg-el-image-wrap has-thumbnail\">\n\t\t\t\t\t<a data-id=\"18116\" href=\"https:\/\/prodelcobre.cl\/nueva\/copec-emoac-y-sonnedix-concretan-tres-ppas-para-impulsar-proyecto-de-almacenamiento-en-el-norte-de-chile\/\" class=\"tpg-post-link\" target=\"_self\"><img loading=\"lazy\" width=\"640\" height=\"360\" src=\"https:\/\/prodelcobre.cl\/nueva\/wp-content\/uploads\/2026\/04\/El-Industrial-edicion-Diciembre-2025-Enero-2026-53-768x432.png\" class=\"attachment-medium_large size-medium_large wp-post-image\" alt=\"El Industrial edici\u00f3n Diciembre 2025 - Enero 2026 (53)\" srcset=\"https:\/\/prodelcobre.cl\/nueva\/wp-content\/uploads\/2026\/04\/El-Industrial-edicion-Diciembre-2025-Enero-2026-53-768x432.png 768w, https:\/\/prodelcobre.cl\/nueva\/wp-content\/uploads\/2026\/04\/El-Industrial-edicion-Diciembre-2025-Enero-2026-53-1536x864.png 1536w, https:\/\/prodelcobre.cl\/nueva\/wp-content\/uploads\/2026\/04\/El-Industrial-edicion-Diciembre-2025-Enero-2026-53-2048x1152.png 2048w, https:\/\/prodelcobre.cl\/nueva\/wp-content\/uploads\/2026\/04\/El-Industrial-edicion-Diciembre-2025-Enero-2026-53-1024x576.png 1024w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" loading=\"lazy\" decoding=\"async\" \/>\t\t\n\t\t<\/a>\n\t\t        <div class=\"overlay grid-hover-content\"><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\n\t\t\t<div class=\"post-right-content\">\n\n\t\t\t\t<div class=\"entry-title-wrapper\"><h4 class=\"entry-title\"><a data-id=\"18116\" href=\"https:\/\/prodelcobre.cl\/nueva\/copec-emoac-y-sonnedix-concretan-tres-ppas-para-impulsar-proyecto-de-almacenamiento-en-el-norte-de-chile\/\" class=\"tpg-post-link\" target=\"_self\">Copec EMOAC y Sonnedix concretan tres PPAs para impulsar proyecto de almacenamiento en el norte de Chile<\/a><\/h4><\/div>\n\n\t\t\t\t\t\t\t\t\t<div class=\"post-meta-tags rt-el-post-meta\">\n\t\t\t\t\t\t            <span class='date'>\n\t\t\t\t<i class='far fa-calendar-alt '><\/i>\t\t\t\t                    <a href=\"https:\/\/prodelcobre.cl\/nueva\/2026\/04\/25\/\">\n\t\t\t\t\tAbril 25, 2026\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\n\n<\/div> <!--End right offset column -->\n\n\n\n\n\t<!--Start right offset column -->\n\t<div class=\"rt-col-md-6 rt-col-sm-12 rt-col-xs-12 default rt-list-item rt-grid-item\" data-id=\"18088\">\n\n\n\t<div class=\"rt-holder tpg-post-holder \">\n\t\t<div class=\"rt-detail rt-el-content-wrapper\">\n\t\t\t\t\t\t\t<div class=\"rt-img-holder tpg-el-image-wrap has-thumbnail\">\n\t\t\t\t\t<a data-id=\"18088\" href=\"https:\/\/prodelcobre.cl\/nueva\/chile-refuerza-su-rol-como-plataforma-clave-para-la-infraestructura-energetica-en-america-latina\/\" class=\"tpg-post-link\" target=\"_self\"><img loading=\"lazy\" width=\"640\" height=\"360\" src=\"https:\/\/prodelcobre.cl\/nueva\/wp-content\/uploads\/2026\/04\/El-Industrial-edicion-Diciembre-2025-Enero-2026-52-768x432.png\" class=\"attachment-medium_large size-medium_large wp-post-image\" alt=\"El Industrial edici\u00f3n Diciembre 2025 - Enero 2026 (52)\" srcset=\"https:\/\/prodelcobre.cl\/nueva\/wp-content\/uploads\/2026\/04\/El-Industrial-edicion-Diciembre-2025-Enero-2026-52-768x432.png 768w, https:\/\/prodelcobre.cl\/nueva\/wp-content\/uploads\/2026\/04\/El-Industrial-edicion-Diciembre-2025-Enero-2026-52-1536x864.png 1536w, https:\/\/prodelcobre.cl\/nueva\/wp-content\/uploads\/2026\/04\/El-Industrial-edicion-Diciembre-2025-Enero-2026-52-2048x1152.png 2048w, https:\/\/prodelcobre.cl\/nueva\/wp-content\/uploads\/2026\/04\/El-Industrial-edicion-Diciembre-2025-Enero-2026-52-1024x576.png 1024w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" loading=\"lazy\" decoding=\"async\" \/>\t\t\n\t\t<\/a>\n\t\t        <div class=\"overlay grid-hover-content\"><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\n\t\t\t<div class=\"post-right-content\">\n\n\t\t\t\t<div class=\"entry-title-wrapper\"><h4 class=\"entry-title\"><a data-id=\"18088\" href=\"https:\/\/prodelcobre.cl\/nueva\/chile-refuerza-su-rol-como-plataforma-clave-para-la-infraestructura-energetica-en-america-latina\/\" class=\"tpg-post-link\" target=\"_self\">Chile refuerza su rol como plataforma clave para la infraestructura energ\u00e9tica en Am\u00e9rica Latina<\/a><\/h4><\/div>\n\n\t\t\t\t\t\t\t\t\t<div class=\"post-meta-tags rt-el-post-meta\">\n\t\t\t\t\t\t            <span class='date'>\n\t\t\t\t<i class='far fa-calendar-alt '><\/i>\t\t\t\t                    <a href=\"https:\/\/prodelcobre.cl\/nueva\/2026\/04\/23\/\">\n\t\t\t\t\tAbril 23, 2026\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\n\n<\/div> <!--End right offset column -->\n\n\n\n\n\t<!--Start right offset column -->\n\t<div class=\"rt-col-md-6 rt-col-sm-12 rt-col-xs-12 default rt-list-item rt-grid-item\" data-id=\"18010\">\n\n\n\t<div class=\"rt-holder tpg-post-holder \">\n\t\t<div class=\"rt-detail rt-el-content-wrapper\">\n\t\t\t\t\t\t\t<div class=\"rt-img-holder tpg-el-image-wrap has-thumbnail\">\n\t\t\t\t\t<a data-id=\"18010\" href=\"https:\/\/prodelcobre.cl\/nueva\/consumo-electrico-en-la-mineria-del-cobre-seguiria-al-alza-y-superaria-los-33-twh-hacia-2034\/\" class=\"tpg-post-link\" target=\"_self\"><img loading=\"lazy\" width=\"640\" height=\"480\" src=\"https:\/\/prodelcobre.cl\/nueva\/wp-content\/uploads\/2026\/04\/622334775_893862709667435_4912848546249956610_n-768x576.jpg\" class=\"attachment-medium_large size-medium_large wp-post-image\" alt=\"622334775_893862709667435_4912848546249956610_n\" srcset=\"https:\/\/prodelcobre.cl\/nueva\/wp-content\/uploads\/2026\/04\/622334775_893862709667435_4912848546249956610_n-768x576.jpg 768w, https:\/\/prodelcobre.cl\/nueva\/wp-content\/uploads\/2026\/04\/622334775_893862709667435_4912848546249956610_n-1536x1152.jpg 1536w, https:\/\/prodelcobre.cl\/nueva\/wp-content\/uploads\/2026\/04\/622334775_893862709667435_4912848546249956610_n-1024x768.jpg 1024w, https:\/\/prodelcobre.cl\/nueva\/wp-content\/uploads\/2026\/04\/622334775_893862709667435_4912848546249956610_n.jpg 1920w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" loading=\"lazy\" decoding=\"async\" \/>\t\t\n\t\t<\/a>\n\t\t        <div class=\"overlay grid-hover-content\"><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\n\t\t\t<div class=\"post-right-content\">\n\n\t\t\t\t<div class=\"entry-title-wrapper\"><h4 class=\"entry-title\"><a data-id=\"18010\" href=\"https:\/\/prodelcobre.cl\/nueva\/consumo-electrico-en-la-mineria-del-cobre-seguiria-al-alza-y-superaria-los-33-twh-hacia-2034\/\" class=\"tpg-post-link\" target=\"_self\">Consumo el\u00e9ctrico en la miner\u00eda del cobre seguir\u00eda al alza y superar\u00eda los 33 TWh hacia 2034<\/a><\/h4><\/div>\n\n\t\t\t\t\t\t\t\t\t<div class=\"post-meta-tags rt-el-post-meta\">\n\t\t\t\t\t\t            <span class='date'>\n\t\t\t\t<i class='far fa-calendar-alt '><\/i>\t\t\t\t                    <a href=\"https:\/\/prodelcobre.cl\/nueva\/2026\/04\/17\/\">\n\t\t\t\t\tAbril 17, 2026\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\n\n<\/div> <!--End right offset column -->\n\n\n\n\n\t<!--Start right offset column -->\n\t<div class=\"rt-col-md-6 rt-col-sm-12 rt-col-xs-12 default rt-list-item rt-grid-item\" data-id=\"17807\">\n\n\n\t<div class=\"rt-holder tpg-post-holder \">\n\t\t<div class=\"rt-detail rt-el-content-wrapper\">\n\t\t\t\t\t\t\t<div class=\"rt-img-holder tpg-el-image-wrap has-thumbnail\">\n\t\t\t\t\t<a data-id=\"17807\" href=\"https:\/\/prodelcobre.cl\/nueva\/gestion-hidrica-sustentable-el-compromiso-de-lundin-mining-candelaria-en-atacama\/\" class=\"tpg-post-link\" target=\"_self\"><img loading=\"lazy\" width=\"640\" height=\"384\" src=\"https:\/\/prodelcobre.cl\/nueva\/wp-content\/uploads\/2026\/03\/DiaMundialdelAgua-Lundin-Mining-Candelaria-01-768x461.jpg\" class=\"attachment-medium_large size-medium_large wp-post-image\" alt=\"DiaMundialdelAgua-Lundin-Mining-Candelaria-01\" srcset=\"https:\/\/prodelcobre.cl\/nueva\/wp-content\/uploads\/2026\/03\/DiaMundialdelAgua-Lundin-Mining-Candelaria-01-768x461.jpg 768w, https:\/\/prodelcobre.cl\/nueva\/wp-content\/uploads\/2026\/03\/DiaMundialdelAgua-Lundin-Mining-Candelaria-01-1024x615.jpg 1024w, https:\/\/prodelcobre.cl\/nueva\/wp-content\/uploads\/2026\/03\/DiaMundialdelAgua-Lundin-Mining-Candelaria-01.jpg 1200w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" loading=\"lazy\" decoding=\"async\" \/>\t\t\n\t\t<\/a>\n\t\t        <div class=\"overlay grid-hover-content\"><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\n\t\t\t<div class=\"post-right-content\">\n\n\t\t\t\t<div class=\"entry-title-wrapper\"><h4 class=\"entry-title\"><a data-id=\"17807\" href=\"https:\/\/prodelcobre.cl\/nueva\/gestion-hidrica-sustentable-el-compromiso-de-lundin-mining-candelaria-en-atacama\/\" class=\"tpg-post-link\" target=\"_self\">Gesti\u00f3n h\u00eddrica sustentable: el compromiso de Lundin Mining Candelaria en Atacama<\/a><\/h4><\/div>\n\n\t\t\t\t\t\t\t\t\t<div class=\"post-meta-tags rt-el-post-meta\">\n\t\t\t\t\t\t            <span class='date'>\n\t\t\t\t<i class='far fa-calendar-alt '><\/i>\t\t\t\t                    <a href=\"https:\/\/prodelcobre.cl\/nueva\/2026\/03\/22\/\">\n\t\t\t\t\tMarzo 22, 2026\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\n\n<\/div> <!--End right offset column -->\n\n\n\n\n\t<!--Start right offset column -->\n\t<div class=\"rt-col-md-6 rt-col-sm-12 rt-col-xs-12 default rt-list-item rt-grid-item\" data-id=\"17138\">\n\n\n\t<div class=\"rt-holder tpg-post-holder \">\n\t\t<div class=\"rt-detail rt-el-content-wrapper\">\n\t\t\t\t\t\t\t<div class=\"rt-img-holder tpg-el-image-wrap has-thumbnail\">\n\t\t\t\t\t<a data-id=\"17138\" href=\"https:\/\/prodelcobre.cl\/nueva\/antofagasta-plc-se-posiciona-entre-las-20-mineras-mas-valiosas-del-mundo\/\" class=\"tpg-post-link\" target=\"_self\"><img loading=\"lazy\" width=\"640\" height=\"350\" src=\"https:\/\/prodelcobre.cl\/nueva\/wp-content\/uploads\/2021\/08\/ECONOMIA-768x420.jpg\" class=\"attachment-medium_large size-medium_large wp-post-image\" alt=\"mercados\" srcset=\"https:\/\/prodelcobre.cl\/nueva\/wp-content\/uploads\/2021\/08\/ECONOMIA-768x420.jpg 768w, https:\/\/prodelcobre.cl\/nueva\/wp-content\/uploads\/2021\/08\/ECONOMIA-1536x841.jpg 1536w, https:\/\/prodelcobre.cl\/nueva\/wp-content\/uploads\/2021\/08\/ECONOMIA.jpg 1920w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" loading=\"lazy\" decoding=\"async\" \/>\t\t\n\t\t<\/a>\n\t\t        <div class=\"overlay grid-hover-content\"><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\n\t\t\t<div class=\"post-right-content\">\n\n\t\t\t\t<div class=\"entry-title-wrapper\"><h4 class=\"entry-title\"><a data-id=\"17138\" href=\"https:\/\/prodelcobre.cl\/nueva\/antofagasta-plc-se-posiciona-entre-las-20-mineras-mas-valiosas-del-mundo\/\" class=\"tpg-post-link\" target=\"_self\">Antofagasta plc se posiciona entre las 20 mineras m\u00e1s valiosas del mundo<\/a><\/h4><\/div>\n\n\t\t\t\t\t\t\t\t\t<div class=\"post-meta-tags rt-el-post-meta\">\n\t\t\t\t\t\t            <span class='date'>\n\t\t\t\t<i class='far fa-calendar-alt '><\/i>\t\t\t\t                    <a href=\"https:\/\/prodelcobre.cl\/nueva\/2026\/01\/15\/\">\n\t\t\t\t\tEnero 15, 2026\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\n\n<\/div> <!--End right offset column --><\/div> <!--End .rt-row -->\n\n<\/div> <!--End Offset left & offset right column-->            <\/div>\n\n\t\t\t\n        <\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-3c7db025 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"3c7db025\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-fc60057\" data-id=\"fc60057\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2d1a4292 elementor-widget elementor-widget-html\" data-id=\"2d1a4292\" data-element_type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<a href=\"https:\/\/www.inquinat.cl\/\" target=\"_blank\" rel\"nofollow\">\n<img src=https:\/\/amagazine.cl\/wp-content\/uploads\/2024\/12\/banner-inquinatr.jpg\" alt=\"banner inquinat\"\/><\/a>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-17cf015d\" data-id=\"17cf015d\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2d3afda8 elementor-widget elementor-widget-html\" data-id=\"2d3afda8\" data-element_type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<a href=\"https:\/\/www.becker-mining.com\/es\" target=\"_blank\"><video autoplay=\"\" loop=\"\" muted=\"\" playsinline=\"\" style=\"max-width: 100%\" height:auto=\"\">\n<source src=\"https:\/\/amagazine.cl\/wp-content\/uploads\/2024\/07\/banner-becker.webm\">\n\t<\/video><\/a>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2c09a936 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2c09a936\" data-element_type=\"section\" id=\"pasatiempo\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-761bdca3\" data-id=\"761bdca3\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-584fb430 section-title-style-style3 meta-visibility-show title_position_default title_hover_border_default title-default img_hover_animation_default meta_position_default grid-hover-overlay-type-always tpg-el-box-border-enable tpg-border-bottom-disable elementor-widget elementor-widget-tpg-list-layout\" data-id=\"584fb430\" data-element_type=\"widget\" data-widget_type=\"tpg-list-layout.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n        <div class=\"rt-container-fluid rt-tpg-container tpg-el-main-wrapper list-layout1-main \"\n             data-sc-id=\"elementor\"\n             id=\"rt-tpg-container-2458536702\"\n             data-layout=\"list-layout1\"\n             data-grid-style=\"tpg-even\"\n             data-el-settings=''\n             data-el-query=''\n             data-el-path=''\n        >\n\t\t\t            <div class='tpg-header-wrapper '>\n\t\t\t\t\n        <div class=\"tpg-widget-heading-wrapper rt-clear heading-style3 \">\n            <span class=\"tpg-widget-heading-line line-left\"><\/span>\n\t\t\t<h3 class='tpg-widget-heading'>\n\t\t\t\n\t\t\t\t                    <span>\n\t\t\t\t\t\tPasatiempo\t\t\t\t\t<\/span>\n\t\t\t\t\t\n\t\t\t\t\t\t\t<\/h3>            <span class=\"tpg-widget-heading-line line-right\"><\/span>\n\n\t\t\t\n        <\/div>\n\n\t\t\n\t\t            <\/div>\n\n            <div data-title=\"Loading ...\" class=\"rt-row rt-content-loader list-layout1 tpg-even list-behaviour list-layout-wrapper\">\n\t\t\t\t\n<div class=\"rt-col-md-12 rt-col-sm-12 rt-col-xs-12 default rt-list-item rt-grid-item\" data-id=\"13292\">\n\t<div class=\"rt-holder tpg-post-holder \">\n\t\t<div class=\"rt-detail rt-el-content-wrapper\">\n\t\t\t\t\t\t\t<div class=\"rt-img-holder tpg-el-image-wrap has-thumbnail\">\n\t\t\t\t\t<a data-id=\"13292\" href=\"https:\/\/prodelcobre.cl\/nueva\/seminario-desafios-de-la-mineria-2024\/\" class=\"tpg-post-link\" target=\"_self\">                        <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/prodelcobre.cl\/nueva\/wp-content\/uploads\/2023\/11\/Seminario-3-768x576.jpg\"\n                             class=\"rt-img-responsive\"\n                             width=\"640\"\n                             height=\"480\"\n                             alt=\"Calama recibir\u00e1 Seminario Desaf\u00edos de la Miner\u00eda en su edici\u00f3n 2024\">\n\t\t\t\t\t\t\n\t\t\t\t\t\t\t\n\t\t<\/a>\n\t\t        <div class=\"overlay grid-hover-content\"><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\n\t\t\t<div class=\"post-right-content\">\n\t\t\t\t<div class=\"entry-title-wrapper\"><h4 class=\"entry-title\"><a data-id=\"13292\" href=\"https:\/\/prodelcobre.cl\/nueva\/seminario-desafios-de-la-mineria-2024\/\" class=\"tpg-post-link\" target=\"_self\">Calama recibir\u00e1 Seminario Desaf\u00edos de la Miner\u00eda en su edici\u00f3n 2024<\/a><\/h4><\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"post-meta-tags rt-el-post-meta\">\n\t\t\t\t\t\t            <span class='date'>\n\t\t\t\t<i class='far fa-calendar-alt '><\/i>\t\t\t\t                    <a href=\"https:\/\/prodelcobre.cl\/nueva\/2024\/10\/07\/\">\n\t\t\t\t\tOctubre 7, 2024\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"tpg-excerpt tpg-el-excerpt\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"tpg-excerpt-inner\">\n\t\t\t\t\t\t\t\tEl evento que analiza los desaf\u00edos de la industria de cara al 2030 se llevar\u00e1 a cabo en...\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\n<div class=\"rt-col-md-12 rt-col-sm-12 rt-col-xs-12 default rt-list-item rt-grid-item\" data-id=\"3951\">\n\t<div class=\"rt-holder tpg-post-holder \">\n\t\t<div class=\"rt-detail rt-el-content-wrapper\">\n\t\t\t\t\t\t\t<div class=\"rt-img-holder tpg-el-image-wrap has-no-thumbnail\">\n\t\t\t\t\t<a data-id=\"3951\" href=\"https:\/\/prodelcobre.cl\/nueva\/el-niquel-fue-el-rey-en-el-despliegue-de-la-capacidad-de-la-bateria-para-vehiculos-electricos-en-2020\/\" class=\"tpg-post-link\" target=\"_self\">\t\t\n\t\t<\/a>\n\t\t        <div class=\"overlay grid-hover-content\"><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\n\t\t\t<div class=\"post-right-content\">\n\t\t\t\t<div class=\"entry-title-wrapper\"><h4 class=\"entry-title\"><a data-id=\"3951\" href=\"https:\/\/prodelcobre.cl\/nueva\/el-niquel-fue-el-rey-en-el-despliegue-de-la-capacidad-de-la-bateria-para-vehiculos-electricos-en-2020\/\" class=\"tpg-post-link\" target=\"_self\">El n\u00edquel fue el rey en el despliegue de la capacidad de la bater\u00eda para veh\u00edculos el\u00e9ctricos en 2020<\/a><\/h4><\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"post-meta-tags rt-el-post-meta\">\n\t\t\t\t\t\t            <span class='date'>\n\t\t\t\t<i class='far fa-calendar-alt '><\/i>\t\t\t\t                    <a href=\"https:\/\/prodelcobre.cl\/nueva\/2021\/02\/17\/\">\n\t\t\t\t\tFebrero 17, 2021\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"tpg-excerpt tpg-el-excerpt\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"tpg-excerpt-inner\">\n\t\t\t\t\t\t\t\tfuente: adamas intelligence\/ mining.com\/ traducci\u00f3n libre de Profesionales del Cobre Un informe de Adamas Intelligence afirma que m\u00e1s...\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\n<div class=\"rt-col-md-12 rt-col-sm-12 rt-col-xs-12 default rt-list-item rt-grid-item\" data-id=\"3948\">\n\t<div class=\"rt-holder tpg-post-holder \">\n\t\t<div class=\"rt-detail rt-el-content-wrapper\">\n\t\t\t\t\t\t\t<div class=\"rt-img-holder tpg-el-image-wrap has-thumbnail\">\n\t\t\t\t\t<a data-id=\"3948\" href=\"https:\/\/prodelcobre.cl\/nueva\/biden-sienta-las-bases-para-el-auge-de-la-energia-eolica-marina-en-ee-uu\/\" class=\"tpg-post-link\" target=\"_self\">                        <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/prodelcobre.cl\/nueva\/wp-content\/uploads\/2021\/02\/biden-sienta-bases-para-auge-energia-eolica-marina-eeuu-10668-768x480.jpg\"\n                             class=\"rt-img-responsive\"\n                             width=\"640\"\n                             height=\"400\"\n                             alt=\"Biden sienta las bases para el auge de la energ\u00eda e\u00f3lica marina en EE. UU.\">\n\t\t\t\t\t\t\n\t\t\t\t\t\t\t\n\t\t<\/a>\n\t\t        <div class=\"overlay grid-hover-content\"><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\n\t\t\t<div class=\"post-right-content\">\n\t\t\t\t<div class=\"entry-title-wrapper\"><h4 class=\"entry-title\"><a data-id=\"3948\" href=\"https:\/\/prodelcobre.cl\/nueva\/biden-sienta-las-bases-para-el-auge-de-la-energia-eolica-marina-en-ee-uu\/\" class=\"tpg-post-link\" target=\"_self\">Biden sienta las bases para el auge de la energ\u00eda e\u00f3lica marina en EE. UU.<\/a><\/h4><\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"post-meta-tags rt-el-post-meta\">\n\t\t\t\t\t\t            <span class='date'>\n\t\t\t\t<i class='far fa-calendar-alt '><\/i>\t\t\t\t                    <a href=\"https:\/\/prodelcobre.cl\/nueva\/2021\/02\/17\/\">\n\t\t\t\t\tFebrero 17, 2021\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"tpg-excerpt tpg-el-excerpt\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"tpg-excerpt-inner\">\n\t\t\t\t\t\t\t\tEn los Estados Unidos, realmente a\u00fan no se ha dado el despegue de la energ\u00eda e\u00f3lica marina, solo...\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n            <\/div>\n\n\t\t\t\n        <\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-61a24ed3 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"61a24ed3\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-37f18c11\" data-id=\"37f18c11\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-50ef25c elementor-widget elementor-widget-html\" data-id=\"50ef25c\" data-element_type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/elindustrial.cl\/wp-content\/uploads\/2026\/05\/BANNER-WEB-CHILE-GPI_final-1024x166.jpg\">\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-155a2b59\" data-id=\"155a2b59\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>BHP presenta su Plan para Pueblos Ind\u00edgenas en Chile 2026-2030 con foco en participaci\u00f3n y desarrollo territorial Mayo<\/p>\n","protected":false},"author":4,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_header_footer","meta":{"footnotes":""},"class_list":["post-16191","page","type-page","status-publish","hentry"],"rttpg_featured_image_url":null,"rttpg_author":{"display_name":"webmaster","author_link":"https:\/\/prodelcobre.cl\/nueva\/author\/webmaster\/"},"rttpg_comment":0,"rttpg_category":"","rttpg_excerpt":"BHP presenta su Plan para Pueblos Ind\u00edgenas en Chile 2026-2030 con foco en participaci\u00f3n y desarrollo territorial Mayo","_links":{"self":[{"href":"https:\/\/prodelcobre.cl\/nueva\/wp-json\/wp\/v2\/pages\/16191","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/prodelcobre.cl\/nueva\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/prodelcobre.cl\/nueva\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/prodelcobre.cl\/nueva\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/prodelcobre.cl\/nueva\/wp-json\/wp\/v2\/comments?post=16191"}],"version-history":[{"count":53,"href":"https:\/\/prodelcobre.cl\/nueva\/wp-json\/wp\/v2\/pages\/16191\/revisions"}],"predecessor-version":[{"id":18292,"href":"https:\/\/prodelcobre.cl\/nueva\/wp-json\/wp\/v2\/pages\/16191\/revisions\/18292"}],"wp:attachment":[{"href":"https:\/\/prodelcobre.cl\/nueva\/wp-json\/wp\/v2\/media?parent=16191"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}